{"id":11345,"date":"2022-08-21T16:47:00","date_gmt":"2022-08-21T16:47:00","guid":{"rendered":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/?p=11345"},"modified":"2022-09-14T14:01:54","modified_gmt":"2022-09-14T14:01:54","slug":"el-escondrijo-de-las-leyes-departamentales","status":"publish","type":"post","link":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/","title":{"rendered":"Leyes bajo llave: muchas normas vigentes son desconocidas para la gente"},"content":{"rendered":"<body><p><\/p><em><strong>Entran en vigencia desde su publicaci\u00f3n, y por ende, deben ser de conocimiento de los pobladores, pero hay normativas que se esconden bajo llave, a las que incluso no tienen acceso los mismos asamble\u00edstas<\/strong> <\/em>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-11346 size-full\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Reportaje-transparencia.jpeg?resize=696%2C453&#038;ssl=1\" alt=\"\" width=\"696\" height=\"453\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Reportaje-transparencia.jpeg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Reportaje-transparencia.jpeg?resize=300%2C195&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Reportaje-transparencia.jpeg?resize=768%2C500&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Reportaje-transparencia.jpeg?resize=696%2C453&amp;ssl=1 696w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><\/p>\n<p><em>Por Paola Palacios y Jes\u00fas Vargas<\/em><\/p>\n<p class=\"p1\">Una ley es una herramienta que norma sobre todo aspectos de inter\u00e9s de toda la poblaci\u00f3n. Sin embargo, en Bolivia, hay algunas normativas que son guardadas \u201cbajo llave\u201d, principalmente aquellas que las autoridades creen que no deben ser de conocimiento p\u00fablico.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p1\">Esto pasa con una serie de leyes departamentales, entre ellas las que determinan la escala salarial de los gobiernos departamentales.<\/p>\n<p class=\"p1\">El equipo de trabajo de Derecho a la Informaci\u00f3n y Comunicaci\u00f3n (DIC) trat\u00f3 de identificar las leyes de escala salarial de los nueve departamentos del pa\u00eds, pero se encontr\u00f3 con una serie de trabas para conocerlas, pese a que deb\u00edan estar publicadas en sus respectivas gacetas.<\/p>\n<p class=\"p2\"><span class=\"Apple-converted-space\">\u00a0<\/span>El objetivo, al revisar estas normas, era conocer el sueldo que perciben los gobernadores, secretarios, directores, asamble\u00edstas y personal p\u00fablico que forma parte de los gobiernos departamentales.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p1\">Los casos m\u00e1s complicados est\u00e1n en los departamentos de Chuquisaca y Potos\u00ed. En la Villa Imperial ni siquiera la solicitud de una asamble\u00edsta fue suficiente para conocer cu\u00e1l es el sueldo del gobernador y del personal del Gobierno Departamental. La respuesta fue silencio.<\/p>\n<p class=\"p1\">En el caso de ambos departamentos, se envi\u00f3 cartas con el requerimiento de acceso a estas leyes, pero no se obtuvo respuesta desde abril hasta agosto de 2022.<\/p>\n<p class=\"p1\">El constitucionalista y docente Javier Conzelmann Castellanos explic\u00f3 a Bolivia Verifica que en estos casos se puede hasta interponer un amparo, tomando en cuenta que las entidades p\u00fablicas que no quieren dar informaci\u00f3n incumplen el art\u00edculo 24 de la <a href=\"https:\/\/www.oas.org\/dil\/esp\/constitucion_bolivia.pdf\">Constituci\u00f3n Pol\u00edtica del Estado<\/a> (CPE).<\/p>\n<blockquote><p>\u201cToda persona tiene derecho a la petici\u00f3n de manera individual o colectiva, sea oral o escrita, y a la obtenci\u00f3n de respuesta formal y pronta. Para el ejercicio de este derecho no se exigir\u00e1 m\u00e1s requisito que la identificaci\u00f3n del peticionario\u201d, dice el citado art\u00edculo.<\/p><\/blockquote>\n<h3><span style=\"text-decoration: underline;\"><strong>Leyes de escala salarial<\/strong><\/span><\/h3>\n<p>Para saber cu\u00e1les son los sueldos de los actuales gobernadores en los nueve departamentos del pa\u00eds, se recurri\u00f3 a los portales web de cada gobierno departamental, encontrando que tan solo cuatro de las nueve p\u00e1ginas ten\u00edan publicadas las leyes de escala salarial completas.<\/p>\n<p>Se hace \u00e9nfasis en que los documentos estuvieran completos, porque en el caso de <a href=\"https:\/\/gacetaoficial.santacruz.gob.bo\/verpdf\/ley-departamental-220\">Santa Cruz<\/a>, si bien la ley se encuentra en la web, no se tienen los anexos donde se pueda apreciar la escala salarial.<\/p>\n<p>Los departamentos que s\u00ed tienen la informaci\u00f3n colgada y al alcance de la poblaci\u00f3n son <a href=\"https:\/\/www.gobernacionlapaz.gob.bo\/archivos\/gaceta\/LD_205.pdf\">La Paz<\/a>, <a href=\"https:\/\/www.oruro.gob.bo\/wp-content\/uploads\/2021\/09\/ESCALA-SALARIAL-GADOR-2021.pdf\">Oruro<\/a>, Pando y Tarija.<\/p>\n<p>En el caso de Beni, Chuquisaca, Cochabamba y Potos\u00ed no se tienen las normativas actualizadas en sus sitios oficiales, por lo que debe recurrirse a cartas que se env\u00eden a la instituci\u00f3n, aunque no siempre se encuentra una respuesta, como fue nuestro caso.<\/p>\n<p>En el <a href=\"https:\/\/chuquisaca.gob.bo\/portal\/?s=escala+salarial\">portal web<\/a> del Gobierno Departamental de Chuquisaca s\u00ed se encuentra la ley departamental de la pasada gesti\u00f3n, \u00a0pero no es posible acceder a la normativa promulgada por el actual gobernador Dami\u00e1n Condori Herrera.<\/p>\n<p>\u201cP\u00e1gina en construcci\u00f3n\u201d, es el mensaje que aparece en el sitio oficial del Gobierno Aut\u00f3nomo Departamental de Chuquisaca.<\/p>\n<p>El equipo de prensa de DIC quiso acceder desde abril de 2022 a esta informaci\u00f3n en el <a href=\"https:\/\/chuquisaca.gob.bo\/portal\/?page_id=14619\">portal oficial<\/a>\u00a0del Gobierno Departamental de Chuquisaca, pero al ingresar al sector de \u201cTransparencia\u201d, donde est\u00e1 la opci\u00f3n de escala salarial, no se encuentra dicha informaci\u00f3n.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-11347 size-full\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Pa%CC%81gina-de-Chuquisaca.png?resize=696%2C356&#038;ssl=1\" alt=\"\" width=\"696\" height=\"356\" loading=\"lazy\"><\/p>\n<h6 style=\"text-align: center;\"><strong>Captura de pantalla del portal del Gobierno Aut\u00f3nomo Departamental de Chuquisaca.<\/strong><\/h6>\n<p>Tambi\u00e9n se remiti\u00f3 en abril una carta formal al Gobierno Departamental de Chuquisaca para conocer la escala salarial, pero no se obtuvo ninguna respuesta hasta la fecha, a pesar de que colegas periodistas se trasladaron hasta las oficinas de Recursos Humanos para solicitar dicha informaci\u00f3n.<\/p>\n<p>Si bien indicaron desde la Direcci\u00f3n de Recursos Humanos que se tendr\u00eda respuesta a la solicitud, la misma no lleg\u00f3 hasta la fecha.<\/p>\n<p>En el caso de Potos\u00ed, se intent\u00f3 obtener esta informaci\u00f3n a trav\u00e9s de los asamble\u00edstas departamentales, pero tampoco tuvieron la informaci\u00f3n requerida.<\/p>\n<p>Una de las asamble\u00edstas contactadas fue Azucena Fuertes Mamani, quien no pudo acceder a la ley, ni siquiera para analizarla.<\/p>\n<p>Tambi\u00e9n se contact\u00f3 al \u00e1rea de Recursos Humanos del Gobierno Departamental de Potos\u00ed, pero tampoco remiti\u00f3 la ley actualizada.\u00a0Los funcionarios p\u00fablicos de esta instancia no respondieron las llamadas telef\u00f3nicas ni los mensajes enviados por WhatsApp.<\/p>\n<p>No se logr\u00f3 acceder a la ley en la que se encuentra detallado el sueldo del gobernador Jhonny Mamani Guti\u00e9rrez.<\/p>\n<p>A diferencia de los anteriores departamentos mencionados en Beni y Cochabamba s\u00ed se pudo conseguir las escalas salariales, aunque las mismas no se encuentran en sus sitios oficiales.<\/p>\n<p>En el caso de Cochabamba, el asamble\u00edsta Pedro Badr\u00e1n Le\u00f3n tuvo que sacarle una fotograf\u00eda a la ley, porque no pudo acceder al documento para proporcion\u00e1rnoslo.<\/p>\n<p>\u00a0<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-11350 size-full\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Escala-salarial-Cochabamba.jpeg?resize=696%2C928&#038;ssl=1\" alt=\"\" width=\"696\" height=\"928\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Escala-salarial-Cochabamba.jpeg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Escala-salarial-Cochabamba.jpeg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Escala-salarial-Cochabamba.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Escala-salarial-Cochabamba.jpeg?resize=696%2C928&amp;ssl=1 696w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><\/p>\n<h6 style=\"text-align: center;\"><strong>Fotograf\u00eda que se nos proporcion\u00f3 que muestra la escala salarial del Gobierno Aut\u00f3nomo Departamental de Cochabamba.<\/strong><\/h6>\n<h3><span style=\"text-decoration: underline;\"><strong>\u00bfPor qu\u00e9 ingresamos inicialmente a estos portales?<\/strong><\/span><\/h3>\n<p>La <a href=\"https:\/\/www.oas.org\/juridico\/pdfs\/mesicic4_blv_ley28168.pdf\">Ley No 28168<\/a> del 17 de mayo de 2005 de transparencia en la gesti\u00f3n p\u00fablica del Poder Ejecutivo en el art\u00edculo 9 indica lo siguiente:<\/p>\n<blockquote><p>\u201cLas personas pueden acceder a la informaci\u00f3n p\u00fablica de manera directa a trav\u00e9s de p\u00e1ginas electr\u00f3nicas, publicaciones o cualquier otro formato de difusi\u00f3n; y de manera indirecta, a trav\u00e9s de la Unidad de Informaci\u00f3n que las m\u00e1ximas Autoridades Ejecutivas habilitar\u00e1n en cada una de las entidades bajo su cargo o\u0301 a trav\u00e9s de la Unidad existente a la que dicha autoridad le delegue expresamente esta funci\u00f3n\u201d.<\/p><\/blockquote>\n<p>En el mismo sentido, el <a href=\"http:\/\/www.oas.org\/es\/sla\/dlc\/mesicic\/docs\/blv_res39.pdf\">Decreto Supremo N 27329<\/a> en el art\u00edculo 3\u00a0 de acceso a la informaci\u00f3n, indica que en el marco de transparencia de la gesti\u00f3n p\u00fablica se establece que todas las instituciones del Poder Ejecutivo, tanto a nivel central como descentralizado, aut\u00e1rquico y desconcentrado deben hacer p\u00fablicos, a trav\u00e9s de las respectivas p\u00e1ginas electr\u00f3nicas o por cualquier otro medio alternativo de cada ministerio, prefectura (actuales gobernaciones) y entidad desconcentrada, las siguientes caracter\u00edsticas e indicadores:<\/p>\n<ul>\n<li>Presupuesto aprobado por el Tesoro General de la Naci\u00f3n (TGN), el n\u00famero de funcionarios y personal eventual pagados por el TGN, as\u00ed como por otras fuentes de financiamiento.<\/li>\n<li>T\u00e9rminos de referencia del personal contratado.<\/li>\n<li>Objetivos y metas planteados en los respectivos programas operativos anuales.<\/li>\n<li>Reportes de ejecuci\u00f3n presupuestaria de manera anual.<\/li>\n<li>Planes anuales de contrataci\u00f3n de bienes y servicios enviado al Sistema de Informaci\u00f3n de Contrataciones del Estado \u2013 Sicoes.<\/li>\n<\/ul>\n<p>A estas normativas debe sumarse la propia Constituci\u00f3n Pol\u00edtica del Estado.<\/p>\n<p>Es decir, seg\u00fan la Constituci\u00f3n y las normativas vigentes, todo ciudadano boliviano tiene derecho a conocer estas leyes, m\u00e1s a\u00fan si se trata de la escala salarial donde se establecen los sueldos de los funcionarios p\u00fablicos.<\/p>\n<h3><strong><span style=\"text-decoration: underline;\">\u00bfQu\u00e9 es la escala salarial?<\/span> <\/strong><\/h3>\n<p>La escala salarial sirve para diferenciar la jerarqu\u00eda, grado de responsabilidad, experiencia y calificaci\u00f3n del trabajador en proporci\u00f3n al monto o salario otorgado, seg\u00fan establece el <a href=\"https:\/\/bolivia.infoleyes.com\/norma\/1176\/decreto-supremo-19464\">Decreto Supremo 19464.<\/a><\/p>\n<p>La <a href=\"http:\/\/www.planificacion.gob.bo\/uploads\/marco-legal\/Ley%20N%C2%B0%20031%20DE%20AUTONOMIAS%20Y%20DESCENTRALIZACION.pdf\">Ley Marco de Autonom\u00edas y Descentralizaci\u00f3n<\/a> (LMAD) de 2010 en el art\u00edculo 113 se\u00f1ala que las entidades territoriales aut\u00f3nomas \u201cestablecen y aprueban su escala salarial\u201d.<\/p>\n<p>La misma normativa indica que la planilla presupuestaria tambi\u00e9n es aprobada por estas entidades en el marco de los criterios y lineamientos de la pol\u00edtica salarial determinada por el nivel central del Estado.<\/p>\n<p>Estos lineamientos son marcados desde el Ministerio de Econom\u00eda y Finanzas que tiene una <a href=\"https:\/\/drive.google.com\/drive\/folders\/1NPSHZj1GhxGT4DMN-8XAAwMD1eFgGAZM\">gu\u00eda<\/a> para la elaboraci\u00f3n de escalas salariales, la cual es dirigida a los gobiernos aut\u00f3nomos departamentales.<\/p>\n<p>En s\u00edntesis, cada gobierno auton\u00f3mico aprueba su propia escala salarial, tomando como base la gu\u00eda establecida desde el Ministerio de Econom\u00eda.<\/p>\n<h3><span style=\"text-decoration: underline;\"><strong>\u00bfQu\u00e9 dice la ley ante una negativa de respuesta sobre informaci\u00f3n de una instituci\u00f3n p\u00fablica?<\/strong><\/span><\/h3>\n<p>La Ley de Transparencia, en el art\u00edculo 15 indica que la negativa justificada a la entrega de la informaci\u00f3n, solo puede fundamentarse por lo siguiente:<\/p>\n<ol>\n<li>Secreto, reserva o confidencialidad establecidas de manera expresa en leyes vigentes, salvo caso de levantamiento de esta calidad por autoridad competente, conforme a lo dispuesto en la normativa vigente.<\/li>\n<li>Inexistencia de la informaci\u00f3n solicitada en los registros o archivos de la entidad.<\/li>\n<li>Falta de competencia para proporcionar la informaci\u00f3n, cuando \u00e9sta le corresponda a otra entidad.<\/li>\n<\/ol>\n<p>Ninguno de los puntos mencionados fueron las consignas por las que no se proporcion\u00f3 las leyes departamentales de escala salarial, donde figuran los sueldos de los gobernadores y personal p\u00fablico de los gobiernos departamentales.<\/p>\n<p>La informaci\u00f3n de las escalas salariales de los gobiernos departamentales debe ser de car\u00e1cter p\u00fablico, pero en la mayor\u00eda de las regiones se encuentra a\u00fan guardada en el m\u00e1s rec\u00f3ndito escondrijo, como si fuese un secreto de Estado.<\/p>\n<p><em>Este reportaje se realiza en el marco del proyecto \u201cPromoviendo la Ley de acceso a la informaci\u00f3n como una herramienta para fortalecer el periodismo en Bolivia\u201d, promovido por el Programa Internacional para el Desarrollo de la Comunidad (PIDC) de la Organizaci\u00f3n de las Naciones Unidas para la Educaci\u00f3n, la Ciencia y la Cultura (Unesco) y la Fundaci\u00f3n para el Periodismo de Bolivia.<\/em><\/p>\n<\/body>","protected":false},"excerpt":{"rendered":"<p>Entran en vigencia desde su publicaci\u00f3n, y por ende, deben ser de conocimiento de los pobladores, pero hay normativas que se esconden bajo llave, a las que incluso no tienen acceso los mismos asamble\u00edstas Por Paola Palacios y Jes\u00fas Vargas Una ley es una herramienta que norma sobre todo aspectos de inter\u00e9s de toda la [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":11346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8],"tags":[15,24,19,21,22,25,23,20,26],"class_list":["post-11345","post","type-post","status-publish","format-standard","has-post-thumbnail","category-reportajes","tag-acceso-a-la-informacion","tag-beni","tag-cochabamba","tag-la-paz","tag-oruro","tag-pando","tag-potosi","tag-santa-cruz","tag-tarija"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leyes bajo llave: muchas normas vigentes son desconocidas para la gente - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leyes bajo llave: muchas normas vigentes son desconocidas para la gente - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Entran en vigencia desde su publicaci\u00f3n, y por ende, deben ser de conocimiento de los pobladores, pero hay normativas que se esconden bajo llave, a las que incluso no tienen acceso los mismos asamble\u00edstas Por Paola Palacios y Jes\u00fas Vargas Una ley es una herramienta que norma sobre todo aspectos de inter\u00e9s de toda la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/\" \/>\n<meta property=\"og:site_name\" content=\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-21T16:47:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-14T14:01:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Reportaje-transparencia.jpeg?fit=900%2C586&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"586\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor DIC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Fperiodismo\" \/>\n<meta name=\"twitter:site\" content=\"@Fperiodismo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor DIC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-escondrijo-de-las-leyes-departamentales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-escondrijo-de-las-leyes-departamentales\\\/\"},\"author\":{\"name\":\"Editor DIC\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/person\\\/3049c83631e141a2988ef5e56a8bca01\"},\"headline\":\"Leyes bajo llave: muchas normas vigentes son desconocidas para la gente\",\"datePublished\":\"2022-08-21T16:47:00+00:00\",\"dateModified\":\"2022-09-14T14:01:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-escondrijo-de-las-leyes-departamentales\\\/\"},\"wordCount\":1630,\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-escondrijo-de-las-leyes-departamentales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Reportaje-transparencia.jpeg?fit=900%2C586&ssl=1\",\"keywords\":[\"Acceso a la informaci\u00f3n\",\"Beni\",\"Cochabamba\",\"La Paz\",\"Oruro\",\"Pando\",\"Potos\u00ed\",\"Santa Cruz\",\"Tarija\"],\"articleSection\":[\"Reportajes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-escondrijo-de-las-leyes-departamentales\\\/\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-escondrijo-de-las-leyes-departamentales\\\/\",\"name\":\"Leyes bajo llave: muchas normas vigentes son desconocidas para la gente - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-escondrijo-de-las-leyes-departamentales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-escondrijo-de-las-leyes-departamentales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Reportaje-transparencia.jpeg?fit=900%2C586&ssl=1\",\"datePublished\":\"2022-08-21T16:47:00+00:00\",\"dateModified\":\"2022-09-14T14:01:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-escondrijo-de-las-leyes-departamentales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-escondrijo-de-las-leyes-departamentales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-escondrijo-de-las-leyes-departamentales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Reportaje-transparencia.jpeg?fit=900%2C586&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Reportaje-transparencia.jpeg?fit=900%2C586&ssl=1\",\"width\":900,\"height\":586},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-escondrijo-de-las-leyes-departamentales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leyes bajo llave: muchas normas vigentes son desconocidas para la gente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#website\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\",\"name\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"description\":\"Reflexionar a la opini\u00f3n p\u00fablica sobre la aprobaci\u00f3n de la Ley de Acceso a la Informaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\",\"name\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-DIC.png?fit=656%2C330&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-DIC.png?fit=656%2C330&ssl=1\",\"width\":656,\"height\":330,\"caption\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FundacionParaelPeriodismo\\\/\",\"https:\\\/\\\/x.com\\\/Fperiodismo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/person\\\/3049c83631e141a2988ef5e56a8bca01\",\"name\":\"Editor DIC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23025be48f4ef13e6bdf2e741f82afa869785f994990ac1b5ca317178b6c461c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23025be48f4ef13e6bdf2e741f82afa869785f994990ac1b5ca317178b6c461c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23025be48f4ef13e6bdf2e741f82afa869785f994990ac1b5ca317178b6c461c?s=96&d=mm&r=g\",\"caption\":\"Editor DIC\"},\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leyes bajo llave: muchas normas vigentes son desconocidas para la gente - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/","og_locale":"es_ES","og_type":"article","og_title":"Leyes bajo llave: muchas normas vigentes son desconocidas para la gente - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","og_description":"Entran en vigencia desde su publicaci\u00f3n, y por ende, deben ser de conocimiento de los pobladores, pero hay normativas que se esconden bajo llave, a las que incluso no tienen acceso los mismos asamble\u00edstas Por Paola Palacios y Jes\u00fas Vargas Una ley es una herramienta que norma sobre todo aspectos de inter\u00e9s de toda la [&hellip;]","og_url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/","og_site_name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/","article_published_time":"2022-08-21T16:47:00+00:00","article_modified_time":"2022-09-14T14:01:54+00:00","og_image":[{"width":900,"height":586,"url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Reportaje-transparencia.jpeg?fit=900%2C586&ssl=1","type":"image\/jpeg"}],"author":"Editor DIC","twitter_card":"summary_large_image","twitter_creator":"@Fperiodismo","twitter_site":"@Fperiodismo","twitter_misc":{"Escrito por":"Editor DIC","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/#article","isPartOf":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/"},"author":{"name":"Editor DIC","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/person\/3049c83631e141a2988ef5e56a8bca01"},"headline":"Leyes bajo llave: muchas normas vigentes son desconocidas para la gente","datePublished":"2022-08-21T16:47:00+00:00","dateModified":"2022-09-14T14:01:54+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/"},"wordCount":1630,"publisher":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Reportaje-transparencia.jpeg?fit=900%2C586&ssl=1","keywords":["Acceso a la informaci\u00f3n","Beni","Cochabamba","La Paz","Oruro","Pando","Potos\u00ed","Santa Cruz","Tarija"],"articleSection":["Reportajes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/","name":"Leyes bajo llave: muchas normas vigentes son desconocidas para la gente - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","isPartOf":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/#primaryimage"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Reportaje-transparencia.jpeg?fit=900%2C586&ssl=1","datePublished":"2022-08-21T16:47:00+00:00","dateModified":"2022-09-14T14:01:54+00:00","breadcrumb":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/#primaryimage","url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Reportaje-transparencia.jpeg?fit=900%2C586&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Reportaje-transparencia.jpeg?fit=900%2C586&ssl=1","width":900,"height":586},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-escondrijo-de-las-leyes-departamentales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/"},{"@type":"ListItem","position":2,"name":"Leyes bajo llave: muchas normas vigentes son desconocidas para la gente"}]},{"@type":"WebSite","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#website","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/","name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","description":"Reflexionar a la opini\u00f3n p\u00fablica sobre la aprobaci\u00f3n de la Ley de Acceso a la Informaci\u00f3n","publisher":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization","name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/07\/logo-DIC.png?fit=656%2C330&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/07\/logo-DIC.png?fit=656%2C330&ssl=1","width":656,"height":330,"caption":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/","https:\/\/x.com\/Fperiodismo"]},{"@type":"Person","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/person\/3049c83631e141a2988ef5e56a8bca01","name":"Editor DIC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/23025be48f4ef13e6bdf2e741f82afa869785f994990ac1b5ca317178b6c461c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23025be48f4ef13e6bdf2e741f82afa869785f994990ac1b5ca317178b6c461c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23025be48f4ef13e6bdf2e741f82afa869785f994990ac1b5ca317178b6c461c?s=96&d=mm&r=g","caption":"Editor DIC"},"url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/author\/editor\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/08\/Reportaje-transparencia.jpeg?fit=900%2C586&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/comments?post=11345"}],"version-history":[{"count":0,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/media\/11346"}],"wp:attachment":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/media?parent=11345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/categories?post=11345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/tags?post=11345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}