{"id":11450,"date":"2022-11-11T13:25:43","date_gmt":"2022-11-11T13:25:43","guid":{"rendered":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/?p=11450"},"modified":"2022-11-12T12:45:13","modified_gmt":"2022-11-12T12:45:13","slug":"bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica","status":"publish","type":"post","link":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/","title":{"rendered":"Bolivia, Cuba y Venezuela, los pa\u00edses con m\u00e1s restricciones para acceder a la informaci\u00f3n p\u00fablica"},"content":{"rendered":"<body><p><\/p><strong><i>En esta investigaci\u00f3n se pudo constatar un alto desconocimiento de los funcionarios p\u00fablicos bolivianos a las propias normativas nacionales de acceso a la informaci\u00f3n.\u00a0<\/i><\/strong>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-full wp-image-11451 aligncenter\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?resize=696%2C379&#038;ssl=1\" alt=\"\" width=\"696\" height=\"379\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?resize=300%2C163&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?resize=1024%2C557&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?resize=768%2C418&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?resize=1536%2C836&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?resize=696%2C379&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?resize=1068%2C581&amp;ssl=1 1068w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?w=1392&amp;ssl=1 1392w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><\/p>\n<p><b>Por Adriana Olivera R.\/Periodista\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Los periodistas de verificaci\u00f3n en Bolivia, Cuba y Venezuela tienen algo en com\u00fan, las complicaciones para acceder a datos p\u00fablicos libres en sus pa\u00edses, donde los requerimientos no son atendidos por entidades estatales o se encuentran con trabas burocr\u00e1ticas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En cambio, Argentina, Chile y Guatemala son los pa\u00edses donde la informaci\u00f3n p\u00fablica para verificaci\u00f3n e investigaci\u00f3n est\u00e1 disponible.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Experiencias sobre el tema fueron relatadas al equipo de Bolivia Verifica en el encuentro de verificadores de la red <\/span><a href=\"https:\/\/chequeado.com\/latamchequea2022\/#\/\"><span style=\"font-weight: 400;\">LatamChequea 2022<\/span><\/a><span style=\"font-weight: 400;\"> que fue realizado en octubre en Bogot\u00e1, Colombia.<\/span><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-11452\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-10-07-at-15.52.21.jpeg?resize=500%2C307&#038;ssl=1\" alt=\"\" width=\"500\" height=\"307\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-10-07-at-15.52.21.jpeg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-10-07-at-15.52.21.jpeg?resize=300%2C184&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-10-07-at-15.52.21.jpeg?resize=1024%2C629&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-10-07-at-15.52.21.jpeg?resize=768%2C472&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-10-07-at-15.52.21.jpeg?resize=696%2C427&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-10-07-at-15.52.21.jpeg?resize=1068%2C656&amp;ssl=1 1068w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Latam Chequea<\/span><span style=\"font-weight: 400;\">, es un proyecto regional colaborativo para verificar informaci\u00f3n y luchar contra la \u201cinfodemia\u201d. <\/span><span style=\"font-weight: 400;\">Conforman esta red m\u00e1s de 22 verificadoras de 15 pa\u00edses de Latinoam\u00e9rica y Espa\u00f1a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El com\u00fan denominador de los pa\u00edses donde no hay acceso a informaci\u00f3n p\u00fablica es la ausencia de normativa espec\u00edfica que obligue a los Estados al acceso libre de datos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el caso de Bolivia, si bien en la <\/span><a href=\"https:\/\/www.oas.org\/dil\/esp\/constitucion_bolivia.pdf\"><span style=\"font-weight: 400;\">Constituci\u00f3n Pol\u00edtica del Estado<\/span><\/a><span style=\"font-weight: 400;\"> se\u00a0 determina que el ciudadano tiene el derecho a la informaci\u00f3n, ese mandato no se cumple al 100 por ciento.<\/span><\/p>\n<p><b>\u201cA acceder a la informaci\u00f3n, interpretarla, analizarla y comunicarla libremente, de manera individual o colectiva<\/b><span style=\"font-weight: 400;\">. El Estado garantiza el derecho a la comunicaci\u00f3n y el derecho a la informaci\u00f3n\u201d, dicen los art\u00edculos 21,106 y 242.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el caso de Cuba y Venezuela, no solo no hay normas, sino que existen denuncias de ataques contra periodistas, seg\u00fan se\u00f1ala un <\/span><a href=\"https:\/\/www.sipiapa.org\/notas\/1215543-la-sip-presenta-el-ranquin-la-libertad-prensa-las-americas-2022\"><span style=\"font-weight: 400;\">listado <\/span><\/a><span style=\"font-weight: 400;\">de la Sociedad Interamericana de la Prensa (SIP).<\/span><\/p>\n<h3><b>Incursi\u00f3n de la verificaci\u00f3n<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">En Am\u00e9rica Latina fueron incursionando hace m\u00e1s de una d\u00e9cada los sitios web o medios de comunicaci\u00f3n que se dedican a la verificaci\u00f3n de contenidos falsos y de discursos p\u00fablicos que dan las autoridades gubernamentales o p\u00fablicas (tambi\u00e9n es conocido en ingl\u00e9s como <\/span><i><span style=\"font-weight: 400;\">fact checking)<\/span><\/i><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/chequeado.com\/\"><span style=\"font-weight: 400;\">Chequeado <\/span><\/a><span style=\"font-weight: 400;\">de Argentina fue pionera en esta regi\u00f3n, la verificadora empez\u00f3 a trabajar en el a\u00f1o 2009.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con el objetivo de identificar las desinformaciones que circularon en un a\u00f1o de elecciones nacionales, fue creada <\/span><a href=\"https:\/\/boliviaverifica.bo\/\"><span style=\"font-weight: 400;\">Bolivia Verifica<\/span><\/a><span style=\"font-weight: 400;\"> en el a\u00f1o 2019, un proyecto de la <\/span><a href=\"https:\/\/fundacionperiodismo.org\/\"><span style=\"font-weight: 400;\">Fundaci\u00f3n Para el Periodismo<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desde La Paz se empez\u00f3 a analizar los discursos de candidatos a las elecciones presidenciales. Tambi\u00e9n inici\u00f3 el monitoreo e identificaci\u00f3n de contenidos falsos y enga\u00f1osos que circulaban en las redes sociales.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La metodolog\u00eda de trabajo para la verificaci\u00f3n de hechos y discursos indica que se debe acudir a fuentes personales o documentales para contrastar los datos (al igual que\u00a0 periodismo tradicional o investigativo), con el fin de dar una categor\u00eda de falso, enga\u00f1oso o verdadero al chequeo efectuado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, recurrir a las fuentes del Estado no es un trabajo f\u00e1cil, m\u00e1s a\u00fan si no se tiene una ley que permita el acceso a la informaci\u00f3n p\u00fablica para respaldar los chequeos e incluso, investigaciones.<\/span><\/p>\n<h3><b>\u00bfPor qu\u00e9 es importante que un gobierno tenga los datos abiertos?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Los datos abiertos son bases que permiten su reutilizaci\u00f3n, redistribuci\u00f3n e integraci\u00f3n con otros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cLos datos abiertos pueden ser utilizados, reutilizados y redistribuidos libremente por cualquier persona, y que se encuentran sujetos al requerimiento de atribuci\u00f3n y de compartirse de la misma manera en que aparecen\u201d, explica la fundaci\u00f3n especializada en este tema <\/span><a href=\"https:\/\/opendatahandbook.org\/guide\/es\/what-is-open-data\/\"><span style=\"font-weight: 400;\">\u201cOpen Knowledge\u201d<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las principales caracter\u00edsticas de los datos abiertos son: disponibilidad y acceso.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201c<\/span><span style=\"font-weight: 400;\">Los datos abiertos pueden ayudar a mejorar el flujo de informaci\u00f3n dentro de los gobiernos y entre ellos, y hacen que las decisiones y procesos de gobierno sean m\u00e1s transparentes. Una mayor buena transparencia promueve la rendici\u00f3n de cuentas y la gobernanza, enriquece el debate p\u00fablico y ayuda al combate contra la corrupci\u00f3n\u201d, afirma <\/span><a href=\"https:\/\/opendatacharter.net\/principles-es\/\"><span style=\"font-weight: 400;\">Open Data Charter<\/span><\/a><span style=\"font-weight: 400;\">, organizaci\u00f3n que tambi\u00e9n se dedica a fomentar la informaci\u00f3n p\u00fablica.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cuando un Estado tiene su informaci\u00f3n disponible para la ciudadan\u00eda, pertenece a la <\/span><a href=\"https:\/\/www.opengovpartnership.org\/es\/\"><span style=\"font-weight: 400;\">Alianza de Gobierno Abierto<\/span><\/a><span style=\"font-weight: 400;\"> (la Open Goverment Partnertship en ingl\u00e9s). Dentro de esta asociaci\u00f3n se encuentran m\u00e1s de 80 pa\u00edses. Bolivia, Cuba y Venezuela no son parte de ella.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si bien en Bolivia existe la web <\/span><a href=\"https:\/\/datos.gob.bo\/\"><span style=\"font-weight: 400;\">Datos Abiertos<\/span><\/a><span style=\"font-weight: 400;\">, en este sitio solo se encuentra informaci\u00f3n de ocho instituciones gubernamentales y est\u00e1 habilitado a 43 temas. La actualizaci\u00f3n de la mayor\u00eda de estos conjuntos est\u00e1 hasta el a\u00f1o 2020.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En cambio, los datos cerrados se encuentran en formatos m\u00e1s comunes como PDF en los que no se permite realizar cambios.\u00a0\u00a0<\/span><\/p>\n<h3><b>Acceso a datos p\u00fablicos<\/b><\/h3>\n<ul>\n<li aria-level=\"1\"><b>Bolivia<\/b><\/li>\n<\/ul>\n<p>Bolivia, Cuba y Venezuela son pa\u00edses donde no se cuentan con datos actualizados, cuyos gobiernos tardan en entregar informaci\u00f3n p\u00fablica o simplemente no las contestan.<br>\n<b><\/b><\/p>\n<p><span style=\"font-weight: 400;\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-11453\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-2-1.jpg?resize=500%2C500&#038;ssl=1\" alt=\"\" width=\"500\" height=\"500\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-2-1.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-2-1.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-2-1.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-2-1.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-2-1.jpg?resize=696%2C696&amp;ssl=1 696w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>Joaqu\u00edn Martela, periodista y fact checker de Bolivia Verifica, relata los obst\u00e1culos que afront\u00f3 para conseguir informaci\u00f3n p\u00fablica. En el Ministerio de Salud, por ejemplo, le dijeron que no consideraban como periodismo al trabajo de verificaci\u00f3n.<br>\n<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cEnvi\u00e9 una carta al jefe de Comunicaci\u00f3n del Ministerio de Salud, Iv\u00e1n Ayaviri, para solicitar informaci\u00f3n sobre el Programa Nacional de Enfermedades Infectocontagiosas. Mi solicitud no fue atendida dentro de las 72 horas. Despu\u00e9s de dos semanas me comuniqu\u00e9 por tel\u00e9fono y el funcionario dijo que no pod\u00eda darme informaci\u00f3n debido a que estaban \u2018muy ocupados\u2019 con otros asuntos y que el medio en el que trabajo no es period\u00edstico\u201d.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El funcionario estatal dijo a Martela que el periodismo de verificaci\u00f3n \u201cno existe\u201d y que por esa raz\u00f3n no se le entregar\u00e1 la documentaci\u00f3n solicitada, pese a que el tema por el que se acudi\u00f3 a esa cartera de Estado, era investigativo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La normativa boliviana establece que cualquier ciudadano tiene derecho a solicitar informaci\u00f3n p\u00fablica, no necesariamente que est\u00e9 en alg\u00fan gremio o sea un periodista, la cual mostr\u00f3 desconocer el funcionario.\u00a0\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Situaci\u00f3n similar le ocurri\u00f3 con el Gobierno Aut\u00f3nomo Municipal de El Alto, donde acudi\u00f3 para solicitar informaci\u00f3n de la planilla salarial para contrastar con un dato en la secci\u00f3n de discurso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La Alcald\u00eda de El Alto tard\u00f3 m\u00e1s de un mes en responder la solicitud, pero los datos no estaban abiertos ni actualizados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Contrariamente a los dichos del Director de Comunicaci\u00f3n del Ministerio de Salud,\u00a0 la verificaci\u00f3n se aplica desde hace mucho y\u00a0 est\u00e1 ligado al periodismo investigativo que se empez\u00f3 a realizar en el siglo XIX.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los espacios de verificaci\u00f3n de datos surgen en el a\u00f1o 2003, tal es el caso de FactCheck.org y <\/span><a href=\"https:\/\/www.washingtonpost.com\/news\/fact-checker\/\"><span style=\"font-weight: 400;\">The Fact Checker<\/span><\/a><span style=\"font-weight: 400;\"> que pertenece al The Washington Post, ambos de Estados Unidos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cSi hubiera esa ley podr\u00eda usarla para exigir a los funcionarios que respondan a la prensa, que transparenten su trabajo. De alguna manera esa ley los obligar\u00eda a hablar, no solo con medios de comunicaci\u00f3n, sino con cualquier persona o instituci\u00f3n que est\u00e9 fiscalizando al Estado\u201d, agreg\u00f3 el periodista de Bolivia Verifica<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero esta situaci\u00f3n no solo ocurre con los verificadores, sino tambi\u00e9n con periodistas de diferentes medios de comunicaci\u00f3n del pa\u00eds.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Otro de los casos es de Verdad con Tinta, un medio independiente de Tarija que al hacer una <\/span><a href=\"https:\/\/verdadcontinta.com\/2021\/05\/16\/autoridades-desconocen-impacto-ambiental-de-la-construccion-de-represa-el-carrizal\/\"><span style=\"font-weight: 400;\">investigaci\u00f3n<\/span><\/a><span style=\"font-weight: 400;\"> sobre la construcci\u00f3n de una hidroel\u00e9ctrica envi\u00f3 un requerimiento a la Empresa Nacional de Electricidad (Ende) el a\u00f1o 2021, el cual no fue respondido hasta la fecha.\u00a0\u00a0\u00a0<\/span><\/p>\n<ul>\n<li aria-level=\"1\"><b>Cuba<\/b><\/li>\n<\/ul>\n<p>En Cuba\u00a0 la situaci\u00f3n para acceder a la informaci\u00f3n es m\u00e1s compleja, pero al igual que Bolivia no cuenta con una ley para obtener datos.\u00a0<b><\/b><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-full wp-image-11455 aligncenter\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-3-1.png?resize=473%2C500&#038;ssl=1\" alt=\"\" width=\"473\" height=\"500\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-3-1.png?w=473&amp;ssl=1 473w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-3-1.png?resize=284%2C300&amp;ssl=1 284w\" sizes=\"auto, (max-width: 473px) 100vw, 473px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">\u201cEl acceso a la informaci\u00f3n es s\u00faper complicado porque todo aquello que tiene que ver con datos oficiales, sobre asuntos que ellos consideran que los pueden perjudicar, no existen. Ni en base de datos, ni en medios de prensa oficiales. Est\u00e1 muy controlado. Lo manejan como secreto de Estado\u201d, describe Melissa Cordero, editora de <\/span><a href=\"https:\/\/eltoque.com\/sobre-nosotros\"><span style=\"font-weight: 400;\">El Toque<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las limitaciones dentro de Cuba, no impide que el trabajo de verificaci\u00f3n sea realizado, al contrario, los medios acuden a la base de datos de organismos internacionales que el mismo Estado entrega.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cordero tambi\u00e9n dijo que los medios independientes de Cuba no est\u00e1n dentro de la isla; es decir, trabajan desde otros pa\u00edses para continuar con su labor period\u00edstica. \u201cPor ley, el periodismo independiente est\u00e1 prohibido\u201d, sentenci\u00f3.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El Toque y otros medios de comunicaci\u00f3n est\u00e1n realizando una campa\u00f1a para exigir el acceso a la informaci\u00f3n en Cuba y para que no se manejen los datos p\u00fablicos como si fuesen privados.\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Venezuela<\/b><span style=\"font-weight: 400;\">\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Venezuela tambi\u00e9n presenta dificultades para acceder a\u00a0 la informaci\u00f3n, pues desde el Gobierno no se brindan ni se publican los datos p\u00fablicos. Un ejemplo concreto es que el Estado tampoco comparte las cifras econ\u00f3micas del pa\u00eds.<\/span><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-11454\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-4.jpeg?resize=500%2C375&#038;ssl=1\" alt=\"\" width=\"500\" height=\"375\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-4.jpeg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-4.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-4.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-4.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-4.jpeg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-4.jpeg?resize=696%2C522&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-4.jpeg?resize=1068%2C801&amp;ssl=1 1068w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-4.jpeg?w=1392&amp;ssl=1 1392w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0\u201cHay una pr\u00e1ctica recurrente de no brindar informaci\u00f3n y a eso se suma, en el caso de Venezuela, que no hay una norma expl\u00edcita. Est\u00e1 previsto que tenemos el derecho a pedir informaci\u00f3n al Estado, pero nunca se aprob\u00f3 una ley espec\u00edfica\u201d, describe Andr\u00e9s Ca\u00f1izales, director de la plataforma de <\/span><i><span style=\"font-weight: 400;\">fact checking<\/span><\/i> <a href=\"https:\/\/cotejo.info\/\"><span style=\"font-weight: 400;\">Cotejo.Info<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como El Toque de Cuba, en Cotejo.Info tambi\u00e9n se acude a los datos abiertos de organismos internacionales que recaban informaci\u00f3n del Estado venezolano.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un caso espec\u00edfico es la informaci\u00f3n que entrega a la Organizaci\u00f3n de Pa\u00edses Exportadores de Petr\u00f3leo, tomando en cuenta que el principal ingreso de Venezuela es por la venta de hidrocarburos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los periodistas y verificadores acuden a ese informe para contrastar datos cuando se analiza un discurso referente al tema.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cHemos ido construyendo una base de contactos y de fuentes de la organizaci\u00f3n civil. En Venezuela han surgido varios observatorios; por ejemplo, de la violencia, de la educaci\u00f3n, entre otros\u201d.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ca\u00f1izales explic\u00f3 que existen organizaciones que en \u00e1reas espec\u00edficas est\u00e1n recopilando datos e informaci\u00f3n, \u201csolemos apelar a ellas\u201d, dijo ante la falta de datos abiertos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En Venezuela tambi\u00e9n existe un <\/span><a href=\"https:\/\/espaciopublico.ong\/balance-2016-2018-acceso-a-la-informacion-publica-en-venezuela\/\"><span style=\"font-weight: 400;\">pedido generalizado<\/span><\/a><span style=\"font-weight: 400;\"> de la ciudadan\u00eda para obtener una ley que garantice que todos los niveles gubernamentales entreguen datos y se tenga acceso a la informaci\u00f3n p\u00fablica.\u00a0<\/span><\/p>\n<h3><b>Leyes que se cumplen a medias<\/b><\/h3>\n<ul>\n<li aria-level=\"1\"><b>Per\u00fa<\/b><\/li>\n<\/ul>\n<p>La <a href=\"https:\/\/www.peru.gob.pe\/normas\/docs\/ley_27806.pdf\">Ley de Transparencia y Acceso a la Informaci\u00f3n P\u00fablica<\/a> es la que se aplica en Per\u00fa. Esta normativa fue aprobada hace 20 a\u00f1os.<br>\n<b><\/b><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-11457\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/dadadf9d-e6ea-45f4-994f-6286d321cc3c.png?resize=500%2C500&#038;ssl=1\" alt=\"\" width=\"500\" height=\"500\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/dadadf9d-e6ea-45f4-994f-6286d321cc3c.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/dadadf9d-e6ea-45f4-994f-6286d321cc3c.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/dadadf9d-e6ea-45f4-994f-6286d321cc3c.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/dadadf9d-e6ea-45f4-994f-6286d321cc3c.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/dadadf9d-e6ea-45f4-994f-6286d321cc3c.png?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/dadadf9d-e6ea-45f4-994f-6286d321cc3c.png?resize=696%2C696&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/dadadf9d-e6ea-45f4-994f-6286d321cc3c.png?resize=1068%2C1069&amp;ssl=1 1068w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/dadadf9d-e6ea-45f4-994f-6286d321cc3c.png?w=1559&amp;ssl=1 1559w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/dadadf9d-e6ea-45f4-994f-6286d321cc3c.png?w=1392&amp;ssl=1 1392w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Irene Ignacio, editora del sitio <\/span><a href=\"https:\/\/larepublica.pe\/verificador\/\"><span style=\"font-weight: 400;\">Verificador<\/span><\/a><span style=\"font-weight: 400;\"> del medio La Rep\u00fablica de Per\u00fa se\u00f1ala que esta ley sirve principalmente para \u201csolicitar informaci\u00f3n sobre vuelos presidenciales y correos electr\u00f3nicos de funcionarios p\u00fablicos\u201d, y que no es necesario indicar las razones porque se hace esta petici\u00f3n, pero a veces \u201cno se cumple del todo\u201d.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cA veces las instituciones no dan la informaci\u00f3n completa o est\u00e1 censurada, pero si un ciudadano considera que su derecho a la informaci\u00f3n ha sido vulnerado puede presentar una queja, ese ya es un camino un poco m\u00e1s engorroso\u201d, explic\u00f3.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Milagros Requena, periodista especializada en datos de La Rep\u00fablica, explic\u00f3 que existen reportes de organizaciones no gubernamentales y de la Defensor\u00eda del Pueblo que se\u00f1alan una deficiencia de la <\/span><a href=\"https:\/\/www.peru.gob.pe\/normas\/docs\/ley_27806.pdf\"><span style=\"font-weight: 400;\">Ley de Transparencia y Acceso a la Informaci\u00f3n P\u00fablica<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-11461\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-7-1.png?resize=500%2C500&#038;ssl=1\" alt=\"\" width=\"500\" height=\"500\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-7-1.png?w=911&amp;ssl=1 911w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-7-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-7-1.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-7-1.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-7-1.png?resize=696%2C696&amp;ssl=1 696w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Dentro del equipo period\u00edstico tambi\u00e9n tuvieron percances con el cumplimiento de la ley, dijo Requena, quien dijo que \u201chubo problemas para acceder a la informaci\u00f3n\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cNos han entregado informaci\u00f3n de manera presencial y con un\u00a0 cobro m\u00ednimo, pese a que no deber\u00eda hacerse, porque as\u00ed la ley lo estipula \u201d, insisti\u00f3.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En esa misma l\u00ednea de incumplimiento de la ley, el equipo de <\/span><a href=\"https:\/\/data.larepublica.pe\/\"><span style=\"font-weight: 400;\">LR Data<\/span><\/a><span style=\"font-weight: 400;\"> tambi\u00e9n afirm\u00f3 que tardaron \u201cmucho tiempo\u201d en recibir la informaci\u00f3n solicitada, pese a que la ley estipula que la respuesta se debe dar en un tiempo de diez d\u00edas h\u00e1biles, pero no se cumple.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cAlgunos de nuestros pedidos a\u00fan no tienen respuesta. Nosotras, desde el equipo, hemos apelado ante el Tribunal de Transparencia que es la instancia m\u00e1xima, pero la respuesta no var\u00eda mucho. Hay\u00a0 colegas que han llevado su caso a los tribunales y los\u00a0 procesos pueden durar hasta un a\u00f1o o m\u00e1s para pedir informaci\u00f3n\u201d, insisti\u00f3 Requena.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para la periodista peruana existe una falta de transparencia de las instituciones p\u00fablicas, porque no presentan datos abiertos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El periodista y cofundador de <\/span><a href=\"https:\/\/ojo-publico.com\/\"><span style=\"font-weight: 400;\">Ojo P\u00fablico<\/span><\/a><span style=\"font-weight: 400;\">, <\/span><span style=\"font-weight: 400;\">David Hidalgo, <\/span><span style=\"font-weight: 400;\">reconoci\u00f3 que existen ministerios del gobierno peruano que tienen datos abiertos y eso facilita el trabajo period\u00edstico.\u00a0<\/span><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-11458\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-6-1.png?resize=500%2C357&#038;ssl=1\" alt=\"\" width=\"500\" height=\"357\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-6-1.png?w=877&amp;ssl=1 877w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-6-1.png?resize=300%2C214&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-6-1.png?resize=768%2C548&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-6-1.png?resize=696%2C497&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-6-1.png?resize=100%2C70&amp;ssl=1 100w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">El periodista peruano dijo que a trav\u00e9s de la ley, la informaci\u00f3n p\u00fablica se debe obtener dentro del rango de siete d\u00edas.\u00a0\u00a0<\/span><\/p>\n<ul>\n<li aria-level=\"1\"><b>M\u00e9xico<\/b><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">En este pa\u00eds se tiene el Instituto Nacional de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales. Seg\u00fan Liliana El\u00f3segui, periodista de <\/span><a href=\"https:\/\/verificado.com.mx\/\"><span style=\"font-weight: 400;\">Verificado<\/span><\/a><span style=\"font-weight: 400;\">, este organismo s\u00ed cumpl\u00eda su funci\u00f3n y ayud\u00f3 a conocer datos a trav\u00e9s de investigaciones period\u00edsticas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, \u201ctodo cambi\u00f3\u201d cuando ingres\u00f3 al mandato Andr\u00e9s L\u00f3pez Obrador.\u00a0<\/span><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-11462\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-8-1.jpg?resize=500%2C500&#038;ssl=1\" alt=\"\" width=\"500\" height=\"500\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-8-1.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-8-1.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-8-1.jpg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">\u201cEn los proyectos emblem\u00e1ticos de su gesti\u00f3n: la construcci\u00f3n de la refiner\u00eda Dos Bocas, el tren Maya, el aeropuerto Felipe \u00c1ngeles, y tambi\u00e9n lo relacionado a la compra de las vacunas y su distribuci\u00f3n, el Gobierno pidi\u00f3 la reserva de la informaci\u00f3n alegando que son temas de \u2018seguridad nacional\u2019\u201d, record\u00f3 la periodista mexicana.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al igual que Per\u00fa, este pa\u00eds tiene impedimento de acceder a una buena informaci\u00f3n de los datos p\u00fablicos que maneja el Estado.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hacer periodismo en M\u00e9xico es complicado, as\u00ed lo refleja el periodista y editor de <\/span><a href=\"https:\/\/www.animalpolitico.com\/sabueso\/\"><span style=\"font-weight: 400;\">El Sabueso<\/span><\/a><span style=\"font-weight: 400;\">, Arturo Ascenci\u00f3n, quien relat\u00f3 que para el Gobierno, los medios son el enemigo. \u201cEs su estrategia narrativa. Es complicada la labor period\u00edstica\u201d.\u00a0<\/span><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-11465\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-9-1.jpg?resize=500%2C500&#038;ssl=1\" alt=\"\" width=\"500\" height=\"500\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-9-1.jpg?w=200&amp;ssl=1 200w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-9-1.jpg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<ul>\n<li aria-level=\"1\"><b>Brasil<\/b><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Brasil tambi\u00e9n tiene su <\/span><a href=\"https:\/\/observatoriop10.cepal.org\/es\/instrumentos\/lei-acesso-informaco-publica-lei-no-12527\"><span style=\"font-weight: 400;\">Ley de Acceso a la Informaci\u00f3n P\u00fablica<\/span><\/a><span style=\"font-weight: 400;\"> pero esta presenta percances al momento de ser ejecutada. Si bien tiene diez a\u00f1os de vigencia, con el Gobierno de Jair Bolsonario, \u201cfue complicado acceder a los datos p\u00fablicos\u201d.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dentro de la petici\u00f3n de informaci\u00f3n, las instituciones gubernamentales retrasan la entrega de datos. Incluso, guardan la informaci\u00f3n hasta seis a\u00f1os, seg\u00fan indica el editor en jefe del <\/span><a href=\"https:\/\/projetocomprova.com.br\/\"><span style=\"font-weight: 400;\">Proyecto Comprova,<\/span><\/a><span style=\"font-weight: 400;\">\u00a0S\u00e9rgio L\u00fcdtke<\/span><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-11464\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-10.jpeg?resize=375%2C500&#038;ssl=1\" alt=\"\" width=\"375\" height=\"500\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-10.jpeg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-10.jpeg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-10.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-10.jpeg?resize=1152%2C1536&amp;ssl=1 1152w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-10.jpeg?resize=696%2C928&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/Imagen-10.jpeg?resize=1068%2C1424&amp;ssl=1 1068w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">\u201cSi algo est\u00e1 siendo investigado sobre el Palacio de la Presidencia, por ejemplo, es muy dif\u00edcil, casi nunca tenemos una respuesta. Eso es un problema, porque para la verificaci\u00f3n algunas veces tenemos pocas fuentes\u201d, explic\u00f3.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En verificaci\u00f3n es m\u00e1s complicado obtener la informaci\u00f3n para desmentir, porque la tardanza de una respuesta hace que la falsedad vuelva a circular cuando ya pas\u00f3 auge.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cPara la verificaci\u00f3n es necesario que se tenga la informaci\u00f3n correcta y m\u00e1s r\u00e1pido posible, para que se pueda, con las otras evidencias de hechos que se tiene, tener una conclusi\u00f3n y que esta verificaci\u00f3n sea vista por lo m\u00e1ximo de personas posible y en el punto espacio de tiempo\u201d, se\u00f1ala el editor en jefe de Comprova.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cuando empez\u00f3 la pandemia en el a\u00f1o 2020, la informaci\u00f3n que se otorgaba desde el Gobierno de Brasil era cambiada, situaci\u00f3n que fue observada por los verificadores.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con esa experiencia, fue realizada una alianza de medios junto a Comprova, lo que permiti\u00f3 trabajar en una base de datos.<\/span><\/p>\n<p><b>\u00bfQu\u00e9 dice la IFCN ante estos casos?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">La <\/span><a href=\"https:\/\/www.poynter.org\/ifcn\/\"><span style=\"font-weight: 400;\">International Fact-Checking Network<\/span><\/a><span style=\"font-weight: 400;\"> (IFCN por sus siglas en ingl\u00e9s) o la Red Internacional de Verificaci\u00f3n de Datos es la organizaci\u00f3n que re\u00fane a todos los verificadores del mundo. Una instancia que respalda el trabajo period\u00edstico.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El director de IFCN Baybars \u00d6rsek declar\u00f3 que se est\u00e1 asesorando a las organizaciones de <\/span><i><span style=\"font-weight: 400;\">fact checking<\/span><\/i><span style=\"font-weight: 400;\"> para que puedan acceder y manejar la informaci\u00f3n que tienen las organizaciones internacionales; por ejemplo el Banco Mundial (BM).\u00a0<\/span><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-11467 size-full\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-11-1.jpg?resize=500%2C500&#038;ssl=1\" alt=\"\" width=\"500\" height=\"500\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-11-1.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-11-1.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-11-1.jpg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">En esa l\u00ednea, agreg\u00f3 que se est\u00e1 trabajando con organismos a nivel global para que tengan m\u00e1s datos abiertos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Baybars \u00d6rsek acot\u00f3 que el problema de acceso libre a la informaci\u00f3n no solo se ve en Latinoam\u00e9rica, sino\u00a0 tambi\u00e9n en el este de Europa y en el norte de \u00c1frica.\u00a0\u00a0<\/span><\/p>\n<h3><b>Pa\u00edses que no tienen problemas para acceder a los datos<\/b><\/h3>\n<ul>\n<li aria-level=\"1\"><b>Argentina<\/b><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Este pa\u00eds tuvo problemas de acceso a la informaci\u00f3n entre 2009 y 2015, pero posteriormente el Gobierno nacional sancion\u00f3 el a\u00f1o 2016 la <\/span><a href=\"https:\/\/observatorioplanificacion.cepal.org\/es\/marcos-regulatorios\/ley-27275-acceso-la-informacion-publica-de-argentina\"><span style=\"font-weight: 400;\">Ley de Acceso a la Informaci\u00f3n P\u00fablica<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta normativa s\u00ed responde a la solicitud de los periodistas, algunas veces tarda, pero se otorgan los datos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Chequeado tiene un <\/span><a href=\"https:\/\/chequeado.com\/proyectos\/centro-de-datos\/\"><span style=\"font-weight: 400;\">Centro de Datos<\/span><\/a><span style=\"font-weight: 400;\"> en el cual se va concentrando la informaci\u00f3n que se solicita al Estado y que puede ser de inter\u00e9s com\u00fan. Por lo general, son datos que el Gobierno no tiene abiertos.\u00a0<\/span><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"aligncenter wp-image-11466\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-12.png?resize=500%2C329&#038;ssl=1\" alt=\"\" width=\"500\" height=\"329\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-12.png?w=1018&amp;ssl=1 1018w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-12.png?resize=300%2C197&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-12.png?resize=768%2C505&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/imagen-12.png?resize=696%2C457&amp;ssl=1 696w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">\u201cHacemos solicitudes formales de informaci\u00f3n y lo vamos armando; a veces\u00a0 son solicitudes que hacemos de manera peri\u00f3dica, entonces, son series que vamos armando\u201d , explic\u00f3 la directora de\u00a0 la verificadora Chequeado, Laura Zommer.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Zommer agreg\u00f3 que el Centro de Datos presenta esa informaci\u00f3n que puedan ser \u201cm\u00e1s sencillos para no expertos\u201d.\u00a0<\/span><\/p>\n<ul>\n<li aria-level=\"1\"><b>Chile<\/b><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Chile cuenta con la <\/span><a href=\"https:\/\/www.bcn.cl\/leychile\/navegar?idNorma=276363\"><span style=\"font-weight: 400;\">Ley 20285<\/span><\/a><span style=\"font-weight: 400;\"> de transparencia de la funci\u00f3n p\u00fablica y de acceso a la informaci\u00f3n de la administraci\u00f3n del Estado. Fue promulgada en el a\u00f1o 2008 y entr\u00f3 en vigencia en 2009.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La entidad que hace cumplir la Ley 20285 es el <\/span><a href=\"https:\/\/www.consejotransparencia.cl\/\"><span style=\"font-weight: 400;\">Consejo de Transparencia<\/span><\/a><span style=\"font-weight: 400;\"> que brinda los datos p\u00fablicos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El director de <\/span><a href=\"https:\/\/www.malaespinacheck.cl\/\"><span style=\"font-weight: 400;\">Mala Espina Check<\/span><\/a><span style=\"font-weight: 400;\">, Tom\u00e1s Mart\u00ednez, explic\u00f3 que en su calidad de verificador no ha tenido \u201cning\u00fan problema\u201d para acceder a los datos p\u00fablicos. \u201cLas instituciones p\u00fablicas tienen un <\/span><i><span style=\"font-weight: 400;\">banner <\/span><\/i><span style=\"font-weight: 400;\">para hacer solicitudes de acceso a informaci\u00f3n\u201d, a\u00f1adi\u00f3.\u00a0<\/span><\/p>\n<ul>\n<li aria-level=\"1\"><b>Guatemala<\/b><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">En Guatemala tambi\u00e9n se tiene la <\/span><a href=\"https:\/\/observatoriop10.cepal.org\/es\/instrumentos\/ley-acceso-la-informacion-publica-decreto-no-57-2008#:~:text=La%20ley%20tiene%20como%20objeto,transparencia%20de%20la%20administraci%C3%B3n%20p%C3%BAblica.\"><span style=\"font-weight: 400;\">Ley de Acceso a la Informaci\u00f3n P\u00fablica<\/span><\/a><span style=\"font-weight: 400;\">. Esta normativa funciona de la misma manera que en Chile, donde las entidades p\u00fablicas deben fijar un espacio en sus sitios webs de acceso a datos p\u00fablicos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Seg\u00fan el periodista Alex Maldonado de <\/span><a href=\"https:\/\/www.agenciaocote.com\/proyectos\/factica\/\"><span style=\"font-weight: 400;\">F\u00e1ctica<\/span><\/a><span style=\"font-weight: 400;\"> de la <\/span><a href=\"https:\/\/www.agenciaocote.com\/\"><span style=\"font-weight: 400;\">Agencia Ocote<\/span><\/a><span style=\"font-weight: 400;\">, para realizar una petici\u00f3n de informaci\u00f3n p\u00fablica\u00a0 se debe realizar mediante la ley. La mayor\u00eda de las entidades cumplen cuando la solicitud es realizada con ese procedimiento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cEl periodo no debe exceder de quince d\u00edas, y si la entidad lo considera, puede resolver darse otro plazo igual, y lo notifican. Tambi\u00e9n pueden rechazar la petici\u00f3n de informaci\u00f3n y el solicitante apelar\u201d.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si el solicitante est\u00e1 inconforme, puede acudir a la Procuradur\u00eda de los Derechos Humanos para que sancione a la entidad.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cNo todos cumplen con los procesos y entrega de informaci\u00f3n, pero depende de lo que uno pida; en un alto porcentaje lo cumplen\u201d.<\/span><\/p>\n<p>Esta investigaci\u00f3n fue realizada con el apoyo del Fondo Concursable de la Fundaci\u00f3n para el Periodismo (FPP) en el marco del proyecto Red de Apoyo y Protecci\u00f3n a Periodistas (RAPP), con el respaldo The Global Media Defence Fund \u2013 UNESCO<\/p>\n<\/body>","protected":false},"excerpt":{"rendered":"<p>En esta investigaci\u00f3n se pudo constatar un alto desconocimiento de los funcionarios p\u00fablicos bolivianos a las propias normativas nacionales de acceso a la informaci\u00f3n.\u00a0 Por Adriana Olivera R.\/Periodista\u00a0 Los periodistas de verificaci\u00f3n en Bolivia, Cuba y Venezuela tienen algo en com\u00fan, las complicaciones para acceder a datos p\u00fablicos libres en sus pa\u00edses, donde los requerimientos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":11451,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8],"tags":[15,27,33,28],"class_list":["post-11450","post","type-post","status-publish","format-standard","has-post-thumbnail","category-reportajes","tag-acceso-a-la-informacion","tag-bolivia","tag-cuba","tag-venezuela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolivia, Cuba y Venezuela, los pa\u00edses con m\u00e1s restricciones para acceder a la informaci\u00f3n p\u00fablica - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolivia, Cuba y Venezuela, los pa\u00edses con m\u00e1s restricciones para acceder a la informaci\u00f3n p\u00fablica - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"En esta investigaci\u00f3n se pudo constatar un alto desconocimiento de los funcionarios p\u00fablicos bolivianos a las propias normativas nacionales de acceso a la informaci\u00f3n.\u00a0 Por Adriana Olivera R.\/Periodista\u00a0 Los periodistas de verificaci\u00f3n en Bolivia, Cuba y Venezuela tienen algo en com\u00fan, las complicaciones para acceder a datos p\u00fablicos libres en sus pa\u00edses, donde los requerimientos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/\" \/>\n<meta property=\"og:site_name\" content=\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-11T13:25:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-12T12:45:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?fit=1920%2C1045&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1045\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Ovando\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Fperiodismo\" \/>\n<meta name=\"twitter:site\" content=\"@Fperiodismo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Ovando\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\\\/\"},\"author\":{\"name\":\"David Ovando\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/person\\\/2a9a08c116fcd2cb60260041e0affc38\"},\"headline\":\"Bolivia, Cuba y Venezuela, los pa\u00edses con m\u00e1s restricciones para acceder a la informaci\u00f3n p\u00fablica\",\"datePublished\":\"2022-11-11T13:25:43+00:00\",\"dateModified\":\"2022-11-12T12:45:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\\\/\"},\"wordCount\":3282,\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1.jpg?fit=1920%2C1045&ssl=1\",\"keywords\":[\"Acceso a la informaci\u00f3n\",\"Bolivia\",\"Cuba\",\"Venezuela\"],\"articleSection\":[\"Reportajes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\\\/\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\\\/\",\"name\":\"Bolivia, Cuba y Venezuela, los pa\u00edses con m\u00e1s restricciones para acceder a la informaci\u00f3n p\u00fablica - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1.jpg?fit=1920%2C1045&ssl=1\",\"datePublished\":\"2022-11-11T13:25:43+00:00\",\"dateModified\":\"2022-11-12T12:45:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1.jpg?fit=1920%2C1045&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1.jpg?fit=1920%2C1045&ssl=1\",\"width\":1920,\"height\":1045},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolivia, Cuba y Venezuela, los pa\u00edses con m\u00e1s restricciones para acceder a la informaci\u00f3n p\u00fablica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#website\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\",\"name\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"description\":\"Reflexionar a la opini\u00f3n p\u00fablica sobre la aprobaci\u00f3n de la Ley de Acceso a la Informaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\",\"name\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-DIC.png?fit=656%2C330&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-DIC.png?fit=656%2C330&ssl=1\",\"width\":656,\"height\":330,\"caption\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FundacionParaelPeriodismo\\\/\",\"https:\\\/\\\/x.com\\\/Fperiodismo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/person\\\/2a9a08c116fcd2cb60260041e0affc38\",\"name\":\"David Ovando\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d13babedbd4837d8f1c73288480a3713dcb1e901ac53bfbdf9d267cf00944193?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d13babedbd4837d8f1c73288480a3713dcb1e901ac53bfbdf9d267cf00944193?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d13babedbd4837d8f1c73288480a3713dcb1e901ac53bfbdf9d267cf00944193?s=96&d=mm&r=g\",\"caption\":\"David Ovando\"},\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/author\\\/david\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolivia, Cuba y Venezuela, los pa\u00edses con m\u00e1s restricciones para acceder a la informaci\u00f3n p\u00fablica - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/","og_locale":"es_ES","og_type":"article","og_title":"Bolivia, Cuba y Venezuela, los pa\u00edses con m\u00e1s restricciones para acceder a la informaci\u00f3n p\u00fablica - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","og_description":"En esta investigaci\u00f3n se pudo constatar un alto desconocimiento de los funcionarios p\u00fablicos bolivianos a las propias normativas nacionales de acceso a la informaci\u00f3n.\u00a0 Por Adriana Olivera R.\/Periodista\u00a0 Los periodistas de verificaci\u00f3n en Bolivia, Cuba y Venezuela tienen algo en com\u00fan, las complicaciones para acceder a datos p\u00fablicos libres en sus pa\u00edses, donde los requerimientos [&hellip;]","og_url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/","og_site_name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/","article_published_time":"2022-11-11T13:25:43+00:00","article_modified_time":"2022-11-12T12:45:13+00:00","og_image":[{"width":1920,"height":1045,"url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?fit=1920%2C1045&ssl=1","type":"image\/jpeg"}],"author":"David Ovando","twitter_card":"summary_large_image","twitter_creator":"@Fperiodismo","twitter_site":"@Fperiodismo","twitter_misc":{"Escrito por":"David Ovando","Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/#article","isPartOf":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/"},"author":{"name":"David Ovando","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/person\/2a9a08c116fcd2cb60260041e0affc38"},"headline":"Bolivia, Cuba y Venezuela, los pa\u00edses con m\u00e1s restricciones para acceder a la informaci\u00f3n p\u00fablica","datePublished":"2022-11-11T13:25:43+00:00","dateModified":"2022-11-12T12:45:13+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/"},"wordCount":3282,"publisher":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?fit=1920%2C1045&ssl=1","keywords":["Acceso a la informaci\u00f3n","Bolivia","Cuba","Venezuela"],"articleSection":["Reportajes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/","name":"Bolivia, Cuba y Venezuela, los pa\u00edses con m\u00e1s restricciones para acceder a la informaci\u00f3n p\u00fablica - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","isPartOf":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/#primaryimage"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?fit=1920%2C1045&ssl=1","datePublished":"2022-11-11T13:25:43+00:00","dateModified":"2022-11-12T12:45:13+00:00","breadcrumb":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/#primaryimage","url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?fit=1920%2C1045&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?fit=1920%2C1045&ssl=1","width":1920,"height":1045},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/bolivia-cuba-y-venezuela-los-paises-con-mas-restricciones-para-acceder-a-la-informacion-publica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/"},{"@type":"ListItem","position":2,"name":"Bolivia, Cuba y Venezuela, los pa\u00edses con m\u00e1s restricciones para acceder a la informaci\u00f3n p\u00fablica"}]},{"@type":"WebSite","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#website","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/","name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","description":"Reflexionar a la opini\u00f3n p\u00fablica sobre la aprobaci\u00f3n de la Ley de Acceso a la Informaci\u00f3n","publisher":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization","name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/07\/logo-DIC.png?fit=656%2C330&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/07\/logo-DIC.png?fit=656%2C330&ssl=1","width":656,"height":330,"caption":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/","https:\/\/x.com\/Fperiodismo"]},{"@type":"Person","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/person\/2a9a08c116fcd2cb60260041e0affc38","name":"David Ovando","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d13babedbd4837d8f1c73288480a3713dcb1e901ac53bfbdf9d267cf00944193?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d13babedbd4837d8f1c73288480a3713dcb1e901ac53bfbdf9d267cf00944193?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d13babedbd4837d8f1c73288480a3713dcb1e901ac53bfbdf9d267cf00944193?s=96&d=mm&r=g","caption":"David Ovando"},"url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/author\/david\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/1.jpg?fit=1920%2C1045&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/comments?post=11450"}],"version-history":[{"count":0,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/media\/11451"}],"wp:attachment":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/media?parent=11450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/categories?post=11450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/tags?post=11450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}