{"id":11518,"date":"2022-11-27T14:51:55","date_gmt":"2022-11-27T14:51:55","guid":{"rendered":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/?p=11518"},"modified":"2022-11-27T14:51:55","modified_gmt":"2022-11-27T14:51:55","slug":"el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion","status":"publish","type":"post","link":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/","title":{"rendered":"EL  \u00d3rgano Judicial, el trabajo de la prensa y el poco acceso a la informaci\u00f3n"},"content":{"rendered":"<body><p><\/p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-11522 aligncenter\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03.jpeg?resize=496%2C372&#038;ssl=1\" alt=\"\" width=\"496\" height=\"372\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03.jpeg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03.jpeg?resize=696%2C522&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03.jpeg?resize=1068%2C801&amp;ssl=1 1068w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03.jpeg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03.jpeg?w=1392&amp;ssl=1 1392w\" sizes=\"auto, (max-width: 496px) 100vw, 496px\" \/>\n<p>La promoci\u00f3n del acceso a la informaci\u00f3n para fortalecer el periodismo en Bolivia concluy\u00f3 en la capital del Estado con la participaci\u00f3n de periodistas de varios medios de comunicaci\u00f3n<\/p>\n<p>Un asunto que afecta sobremanera en la labor diaria de los periodistas en la ciudad de Sucre es la dificultad en la obtenci\u00f3n de informaci\u00f3n con las autoridades del \u00d3rgano Judicial. \u00c9sa fue una de las conclusiones a las que se llegaron en el taller que promueve la promoci\u00f3n del acceso a la informaci\u00f3n, actividad apoyada por la Fundaci\u00f3n para el Periodismo.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-11521 alignleft\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?resize=395%2C296&#038;ssl=1\" alt=\"\" width=\"395\" height=\"296\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?resize=696%2C522&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?resize=1068%2C801&amp;ssl=1 1068w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?w=1392&amp;ssl=1 1392w\" sizes=\"auto, (max-width: 395px) 100vw, 395px\" \/>El encuentro gir\u00f3 en torno a las normas que garantizan el acceso a la informaci\u00f3n, tanto en el \u00e1mbito global como en el nacional, tomando en cuenta la Convenci\u00f3n Americana de Derechos Humanos y la Constituci\u00f3n Pol\u00edtica del Estado, entre otros.<\/p>\n<p>En ese marco, el comunicador argentino Mart\u00edn Becerra \u2014investigador del Consejo Nacional de Investigaciones Cient\u00edficas y T\u00e9cnicas (Conicet) y doctor en Ciencias de la Informaci\u00f3n\u2014 destac\u00f3 que la obtenci\u00f3n de informaci\u00f3n p\u00fablica es importante porque permite ejercer otros derechos.<\/p>\n<p>Carla Barroso, corresponsal de Gigavisi\u00f3n, afirm\u00f3 que existen serios problemas para conseguir informaci\u00f3n de las entidades estatales, principalmente del \u00d3rgano Judicial. \u201cEs imposible acceder a una noticia, a no ser que hagamos vigilia una ma\u00f1ana o varios d\u00edas o esperar que haya actividades del \u00d3rgano Judicial para obtener datos\u201d, asever\u00f3.<\/p>\n<p>El periodista Ramiro Echaz\u00fa dijo que pas\u00f3 m\u00e1s de un mes desde que solicitaron comunicarse con la presidenta del Consejo de la Magistratura, Mirtha Meneses, y hasta ahora no hubo aceptaci\u00f3n, lo que perjudica la labor de los medios de comunicaci\u00f3n.<\/p>\n<p>\u201cLamentablemente, las veces que hemos intentado tener una nota con ella, no dice nada, lo que se convierte en una limitaci\u00f3n\u201d, recalc\u00f3 Echaz\u00fa, quien indic\u00f3 que quieren informaci\u00f3n sobre la renuncia y acusaciones de corrupci\u00f3n contra el antecesor de Meneses, Marvin Molina.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-11520 aligncenter\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-2.jpeg?resize=452%2C339&#038;ssl=1\" alt=\"\" width=\"452\" height=\"339\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-2.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-2.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-2.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-2.jpeg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-2.jpeg?resize=696%2C522&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-2.jpeg?resize=1068%2C801&amp;ssl=1 1068w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-2.jpeg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-2.jpeg?w=1392&amp;ssl=1 1392w\" sizes=\"auto, (max-width: 452px) 100vw, 452px\" \/>De acuerdo con Barroso, el Tribunal Constitucional se cerr\u00f3 a dar informaci\u00f3n, \u201cincluso ni las unidades de comunicaci\u00f3n responden\u201d. Coincidi\u00f3 con la observaci\u00f3n la periodista Alicia Cutipa, quien cont\u00f3 que hubo solicitudes de informaci\u00f3n, pero les negaron en varias oportunidades.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-11519 aligncenter\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-1.jpeg?resize=484%2C363&#038;ssl=1\" alt=\"\" width=\"484\" height=\"363\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-1.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-1.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-1.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-1.jpeg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-1.jpeg?resize=696%2C522&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-1.jpeg?resize=1068%2C801&amp;ssl=1 1068w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-1.jpeg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-1.jpeg?w=1392&amp;ssl=1 1392w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/>Tomando en cuenta que Bolivia y Surinam son los \u00fanicos pa\u00edses en Am\u00e9rica Latina, Becerra pregunt\u00f3 a qu\u00e9 se debe ello en el caso local. Al respecto, el periodista Jhonny Romay coment\u00f3 que es pertinente apoyar una norma \u201cporque no hay instituciones que f\u00e1cilmente otorguen informaci\u00f3n, pese a que mandan solicitudes\u201d.<\/p>\n<p>Echaz\u00fa dijo que la ciudadan\u00eda perdi\u00f3 la fe en la clase pol\u00edtica, por lo que se desconf\u00eda en la aprobaci\u00f3n en el Legislativo. \u201c\u00bfSer\u00e1 que los pol\u00edticos crear\u00e1n un instrumento para autocontrolarse?\u201d, pregunt\u00f3.<\/p>\n<p>La actividad se desarroll\u00f3 en el marco del proyecto promoviendo el acceso a la informaci\u00f3n como una herramienta para fortalecer el periodismo en Bolivia en el marco del Programa Internacional para el Desarrollo de la Comunicaci\u00f3n (PIDC) de la UNESCO y la Fundaci\u00f3n para el Periodismo.<\/p>\n<\/body>","protected":false},"excerpt":{"rendered":"<p>La promoci\u00f3n del acceso a la informaci\u00f3n para fortalecer el periodismo en Bolivia concluy\u00f3 en la capital del Estado con la participaci\u00f3n de periodistas de varios medios de comunicaci\u00f3n Un asunto que afecta sobremanera en la labor diaria de los periodistas en la ciudad de Sucre es la dificultad en la obtenci\u00f3n de informaci\u00f3n con [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11521,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[12,2,13,11],"tags":[3],"class_list":["post-11518","post","type-post","status-publish","format-standard","has-post-thumbnail","category-debates","category-dic","category-encuentros","category-exposiciones","tag-nota"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EL \u00d3rgano Judicial, el trabajo de la prensa y el poco acceso a la informaci\u00f3n - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EL \u00d3rgano Judicial, el trabajo de la prensa y el poco acceso a la informaci\u00f3n - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La promoci\u00f3n del acceso a la informaci\u00f3n para fortalecer el periodismo en Bolivia concluy\u00f3 en la capital del Estado con la participaci\u00f3n de periodistas de varios medios de comunicaci\u00f3n Un asunto que afecta sobremanera en la labor diaria de los periodistas en la ciudad de Sucre es la dificultad en la obtenci\u00f3n de informaci\u00f3n con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-27T14:51:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?fit=1600%2C1200&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tania Frank\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Fperiodismo\" \/>\n<meta name=\"twitter:site\" content=\"@Fperiodismo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tania Frank\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\\\/\"},\"author\":{\"name\":\"Tania Frank\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/person\\\/76866a0a8716e14bd4a78088e79c55ac\"},\"headline\":\"EL \u00d3rgano Judicial, el trabajo de la prensa y el poco acceso a la informaci\u00f3n\",\"datePublished\":\"2022-11-27T14:51:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\\\/\"},\"wordCount\":537,\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?fit=1600%2C1200&ssl=1\",\"keywords\":[\"nota\"],\"articleSection\":[\"Debates\",\"DIC\",\"Encuentros\",\"Exposiciones\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\\\/\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\\\/\",\"name\":\"EL \u00d3rgano Judicial, el trabajo de la prensa y el poco acceso a la informaci\u00f3n - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?fit=1600%2C1200&ssl=1\",\"datePublished\":\"2022-11-27T14:51:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?fit=1600%2C1200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?fit=1600%2C1200&ssl=1\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EL \u00d3rgano Judicial, el trabajo de la prensa y el poco acceso a la informaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#website\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\",\"name\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"description\":\"Reflexionar a la opini\u00f3n p\u00fablica sobre la aprobaci\u00f3n de la Ley de Acceso a la Informaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\",\"name\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-DIC.png?fit=656%2C330&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-DIC.png?fit=656%2C330&ssl=1\",\"width\":656,\"height\":330,\"caption\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FundacionParaelPeriodismo\\\/\",\"https:\\\/\\\/x.com\\\/Fperiodismo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/person\\\/76866a0a8716e14bd4a78088e79c55ac\",\"name\":\"Tania Frank\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g\",\"caption\":\"Tania Frank\"},\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/author\\\/tania\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EL \u00d3rgano Judicial, el trabajo de la prensa y el poco acceso a la informaci\u00f3n - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/","og_locale":"es_ES","og_type":"article","og_title":"EL \u00d3rgano Judicial, el trabajo de la prensa y el poco acceso a la informaci\u00f3n - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","og_description":"La promoci\u00f3n del acceso a la informaci\u00f3n para fortalecer el periodismo en Bolivia concluy\u00f3 en la capital del Estado con la participaci\u00f3n de periodistas de varios medios de comunicaci\u00f3n Un asunto que afecta sobremanera en la labor diaria de los periodistas en la ciudad de Sucre es la dificultad en la obtenci\u00f3n de informaci\u00f3n con [&hellip;]","og_url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/","og_site_name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/","article_published_time":"2022-11-27T14:51:55+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?fit=1600%2C1200&ssl=1","type":"image\/jpeg"}],"author":"Tania Frank","twitter_card":"summary_large_image","twitter_creator":"@Fperiodismo","twitter_site":"@Fperiodismo","twitter_misc":{"Escrito por":"Tania Frank","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/#article","isPartOf":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/"},"author":{"name":"Tania Frank","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/person\/76866a0a8716e14bd4a78088e79c55ac"},"headline":"EL \u00d3rgano Judicial, el trabajo de la prensa y el poco acceso a la informaci\u00f3n","datePublished":"2022-11-27T14:51:55+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/"},"wordCount":537,"publisher":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?fit=1600%2C1200&ssl=1","keywords":["nota"],"articleSection":["Debates","DIC","Encuentros","Exposiciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/","name":"EL \u00d3rgano Judicial, el trabajo de la prensa y el poco acceso a la informaci\u00f3n - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","isPartOf":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/#primaryimage"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?fit=1600%2C1200&ssl=1","datePublished":"2022-11-27T14:51:55+00:00","breadcrumb":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/#primaryimage","url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?fit=1600%2C1200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?fit=1600%2C1200&ssl=1","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-organo-judicial-el-trabajo-de-la-prensa-y-el-poco-acceso-a-la-informacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/"},{"@type":"ListItem","position":2,"name":"EL \u00d3rgano Judicial, el trabajo de la prensa y el poco acceso a la informaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#website","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/","name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","description":"Reflexionar a la opini\u00f3n p\u00fablica sobre la aprobaci\u00f3n de la Ley de Acceso a la Informaci\u00f3n","publisher":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization","name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/07\/logo-DIC.png?fit=656%2C330&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/07\/logo-DIC.png?fit=656%2C330&ssl=1","width":656,"height":330,"caption":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/","https:\/\/x.com\/Fperiodismo"]},{"@type":"Person","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/person\/76866a0a8716e14bd4a78088e79c55ac","name":"Tania Frank","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g","caption":"Tania Frank"},"url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/author\/tania\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-23-at-19.33.03-3.jpeg?fit=1600%2C1200&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/comments?post=11518"}],"version-history":[{"count":0,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/media\/11521"}],"wp:attachment":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/media?parent=11518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/categories?post=11518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/tags?post=11518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}