{"id":11550,"date":"2022-12-01T12:47:28","date_gmt":"2022-12-01T12:47:28","guid":{"rendered":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/?p=11550"},"modified":"2022-12-01T12:48:38","modified_gmt":"2022-12-01T12:48:38","slug":"en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn","status":"publish","type":"post","link":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/","title":{"rendered":"En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN"},"content":{"rendered":"<body><p><\/p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone wp-image-11553\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?resize=335%2C229&#038;ssl=1\" alt=\"\" width=\"335\" height=\"229\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?resize=300%2C205&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?resize=1024%2C700&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?resize=768%2C525&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?resize=696%2C476&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?resize=1068%2C730&amp;ssl=1 1068w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 335px) 100vw, 335px\" \/>\u00a0\u00a0 <img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-medium wp-image-11558\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50.jpeg?resize=300%2C228&#038;ssl=1\" alt=\"\" width=\"300\" height=\"228\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50.jpeg?resize=300%2C228&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50.jpeg?resize=1024%2C778&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50.jpeg?resize=768%2C584&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50.jpeg?resize=696%2C529&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50.jpeg?resize=1068%2C812&amp;ssl=1 1068w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50.jpeg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n<p><strong>En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN<\/strong><\/p>\n<p>En el taller de promoci\u00f3n del acceso a la informaci\u00f3n p\u00fablica que se llev\u00f3 a cabo el lunes 28 de noviembre en la ciudad de Cochabamba \u2014organizado por la Fundaci\u00f3n para el Periodismo\u2014, los periodistas elaboraron un modelo de solicitud de acceso a informaci\u00f3n a entidades del Estado, con temas que se centraron en salud, el Tren Metropolitano y la FELCN.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-11557 aligncenter\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-2.jpeg?resize=449%2C313&#038;ssl=1\" alt=\"\" width=\"449\" height=\"313\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-2.jpeg?resize=300%2C209&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-2.jpeg?resize=1024%2C714&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-2.jpeg?resize=768%2C536&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-2.jpeg?resize=696%2C486&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-2.jpeg?resize=1068%2C745&amp;ssl=1 1068w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-2.jpeg?resize=100%2C70&amp;ssl=1 100w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-2.jpeg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 449px) 100vw, 449px\" \/>Con la direcci\u00f3n del comunicador argentino Mart\u00edn Becerra \u2014investigador del Consejo Nacional de Investigaciones Cient\u00edficas y T\u00e9cnicas (Conicet) y doctor en Ciencias de la Informaci\u00f3n\u2014, trabajadores de varios medios de comunicaci\u00f3n se reunieron en la Universidad Privada Abierta Latinoamericana (UPAL) con el fin de dialogar acerca de la importancia del acceso a la informaci\u00f3n p\u00fablica.<\/p>\n<p>En ese \u00e1mbito, Becerra record\u00f3 que el acceso a la informaci\u00f3n es la puerta para abrir otros derechos fundamentales. \u201cSi la administraci\u00f3n p\u00fablica retacea datos e informaci\u00f3n, entonces el pueblo no est\u00e1 gobernando, sino un estamento del gobierno en nombre de ese pueblo\u201d, razon\u00f3.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-11555 aligncenter\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.33.jpeg?resize=464%2C348&#038;ssl=1\" alt=\"\" width=\"464\" height=\"348\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.33.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.33.jpeg?resize=1024%2C766&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.33.jpeg?resize=768%2C575&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.33.jpeg?resize=696%2C521&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.33.jpeg?resize=1068%2C799&amp;ssl=1 1068w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.33.jpeg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 464px) 100vw, 464px\" \/>Despu\u00e9s de enumerar las normas internacionales y nacionales que garantizan la obtenci\u00f3n de datos del aparato p\u00fablico, como la Convenci\u00f3n Americana de Derechos Humanos y la Constituci\u00f3n Pol\u00edtica del Estado, Norman Chinchilla, periodista de Los Tiempos, cont\u00f3 que en muchos casos tuvo que recurrir directamente a la autoridad para obtener alguna informaci\u00f3n.<\/p>\n<p>\u201cEncontramos que el atajo funciona mejor que invocar la ley, es decir que llamamos al ministro y lo presionas para que d\u00e9 informaci\u00f3n. De alguna manera burlamos el camino para encontrar la informaci\u00f3n que se necesita, pero al hacer esto estamos atentando contra la vigencia de ese derecho (de acceso a la informaci\u00f3n)\u201d, coment\u00f3 Chinchilla.<\/p>\n<p>Como parte del taller se armaron grupos que elaboraron un modelo de carta de petici\u00f3n de acceso a informaci\u00f3n. En ese sentido, Lorena Amurrio, periodista de La Nube, inform\u00f3 que la misiva giraba en torno al Tren Metropolitano, para saber cu\u00e1les son los costos operativos y mecanismos de c\u00e1lculo de los pasajes. Otro punto es saber el procedimiento de selecci\u00f3n y contrataci\u00f3n y cu\u00e1l es el proceso de alquiler de los espacios publicitarios en las estaciones.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-11552 aligncenter\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32-1.jpeg?resize=433%2C319&#038;ssl=1\" alt=\"\" width=\"433\" height=\"319\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32-1.jpeg?resize=300%2C221&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32-1.jpeg?resize=1024%2C756&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32-1.jpeg?resize=768%2C567&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32-1.jpeg?resize=696%2C514&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32-1.jpeg?resize=1068%2C788&amp;ssl=1 1068w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32-1.jpeg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 433px) 100vw, 433px\" \/>Patricia Pinto, corresponsal de Reuters, en nombre de su grupo, explic\u00f3 que su carta era para el ministro de Gobierno, Eduardo del Castillo, con el fin de acceder a informaci\u00f3n de la Fuerza Especial de Lucha contra el Narcotr\u00e1fico (FELCN) sobre cu\u00e1ntas pistas clandestinas ha identificado el Gobierno, en qu\u00e9 zonas se encuentran, saber si el tr\u00f3pico cochabambino es visto como un punto de refinaci\u00f3n o nexo con el narcotr\u00e1fico y cu\u00e1ndo se tiene planeado instalar radares en el pa\u00eds, entre otras. \u201cHemos hecho estas consultas porque hasta ahora no nos han sabido responder\u201d, justific\u00f3.<\/p>\n<p>Antonio Ortiz, comunicador del Concejo Municipal de Cochabamba, inform\u00f3 que la misiva ser\u00eda enviada al Ministerio de Salud para conocer los desembolsos econ\u00f3micos para el tratamiento y prevenci\u00f3n del covid-19 entre 2020 y 2022. \u201cEl objetivo de esta informaci\u00f3n es tener datos precisos anuales, desde que ha iniciado la pandemia, conocer cu\u00e1l ha sido la etapa m\u00e1s \u00e1lgida y saber si estamos en descenso o ascenso, para hacer comparativas en el \u00e1mbito econ\u00f3mico\u201d, explic\u00f3 la periodista independiente Shirley Aguilar.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-11556 alignright\" src=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-1.jpeg?resize=506%2C354&#038;ssl=1\" alt=\"\" width=\"506\" height=\"354\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-1.jpeg?resize=300%2C210&amp;ssl=1 300w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-1.jpeg?resize=1024%2C716&amp;ssl=1 1024w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-1.jpeg?resize=768%2C537&amp;ssl=1 768w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-1.jpeg?resize=696%2C487&amp;ssl=1 696w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-1.jpeg?resize=1068%2C747&amp;ssl=1 1068w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-1.jpeg?resize=100%2C70&amp;ssl=1 100w, https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-15.41.50-1.jpeg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 506px) 100vw, 506px\" \/>Celia Alvarado, de Televisi\u00f3n Universitaria, dijo que escribieron una solicitud dirigida al alcalde de Cochabamba, Manfred Reyes Villa, para pedir la planilla salarial del ejecutivo y del Servicio Municipal de Agua Potable y Alcantarillado (Semapa), de septiembre y octubre de 2021 y 2022. \u201cEste requerimiento es porque se han recibido denuncias de 70 casos de nepotismo. Aparentemente, no s\u00f3lo est\u00e1n trabajando padre e hijo, sino tambi\u00e9n nietos. Es por eso que estamos enviando la solicitud\u201d, justific\u00f3.<\/p>\n<p>Al final del taller, los participantes recibieron una carta modelos de petici\u00f3n de acceso a la informaci\u00f3n, que sirva para el mejor trabajo de los periodistas en el valle boliviano.<\/p>\n<p>La actividad se desarroll\u00f3 en el marco del proyecto promoviendo el acceso a la informaci\u00f3n como una herramienta para fortalecer el periodismo en Bolivia en el marco del Programa Internacional para el Desarrollo de la Comunicaci\u00f3n (PIDC) de la UNESCO y la Fundaci\u00f3n para el Periodismo.<\/p>\n<\/body>","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0 En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN En el taller de promoci\u00f3n del acceso a la informaci\u00f3n p\u00fablica que se llev\u00f3 a cabo el lunes 28 de noviembre en la ciudad de Cochabamba \u2014organizado por la Fundaci\u00f3n para el Periodismo\u2014, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11553,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[12,2,13,11],"tags":[3],"class_list":["post-11550","post","type-post","status-publish","format-standard","has-post-thumbnail","category-debates","category-dic","category-encuentros","category-exposiciones","tag-nota"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"\u00a0\u00a0 En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN En el taller de promoci\u00f3n del acceso a la informaci\u00f3n p\u00fablica que se llev\u00f3 a cabo el lunes 28 de noviembre en la ciudad de Cochabamba \u2014organizado por la Fundaci\u00f3n para el Periodismo\u2014, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/\" \/>\n<meta property=\"og:site_name\" content=\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-01T12:47:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-01T12:48:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?fit=1280%2C875&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tania Frank\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Fperiodismo\" \/>\n<meta name=\"twitter:site\" content=\"@Fperiodismo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tania Frank\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\\\/\"},\"author\":{\"name\":\"Tania Frank\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/person\\\/76866a0a8716e14bd4a78088e79c55ac\"},\"headline\":\"En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN\",\"datePublished\":\"2022-12-01T12:47:28+00:00\",\"dateModified\":\"2022-12-01T12:48:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\\\/\"},\"wordCount\":767,\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?fit=1280%2C875&ssl=1\",\"keywords\":[\"nota\"],\"articleSection\":[\"Debates\",\"DIC\",\"Encuentros\",\"Exposiciones\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\\\/\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\\\/\",\"name\":\"En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?fit=1280%2C875&ssl=1\",\"datePublished\":\"2022-12-01T12:47:28+00:00\",\"dateModified\":\"2022-12-01T12:48:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?fit=1280%2C875&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?fit=1280%2C875&ssl=1\",\"width\":1280,\"height\":875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#website\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\",\"name\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"description\":\"Reflexionar a la opini\u00f3n p\u00fablica sobre la aprobaci\u00f3n de la Ley de Acceso a la Informaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\",\"name\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-DIC.png?fit=656%2C330&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-DIC.png?fit=656%2C330&ssl=1\",\"width\":656,\"height\":330,\"caption\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FundacionParaelPeriodismo\\\/\",\"https:\\\/\\\/x.com\\\/Fperiodismo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/person\\\/76866a0a8716e14bd4a78088e79c55ac\",\"name\":\"Tania Frank\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g\",\"caption\":\"Tania Frank\"},\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/author\\\/tania\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/","og_locale":"es_ES","og_type":"article","og_title":"En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","og_description":"\u00a0\u00a0 En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN En el taller de promoci\u00f3n del acceso a la informaci\u00f3n p\u00fablica que se llev\u00f3 a cabo el lunes 28 de noviembre en la ciudad de Cochabamba \u2014organizado por la Fundaci\u00f3n para el Periodismo\u2014, [&hellip;]","og_url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/","og_site_name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/","article_published_time":"2022-12-01T12:47:28+00:00","article_modified_time":"2022-12-01T12:48:38+00:00","og_image":[{"width":1280,"height":875,"url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?fit=1280%2C875&ssl=1","type":"image\/jpeg"}],"author":"Tania Frank","twitter_card":"summary_large_image","twitter_creator":"@Fperiodismo","twitter_site":"@Fperiodismo","twitter_misc":{"Escrito por":"Tania Frank","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/#article","isPartOf":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/"},"author":{"name":"Tania Frank","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/person\/76866a0a8716e14bd4a78088e79c55ac"},"headline":"En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN","datePublished":"2022-12-01T12:47:28+00:00","dateModified":"2022-12-01T12:48:38+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/"},"wordCount":767,"publisher":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?fit=1280%2C875&ssl=1","keywords":["nota"],"articleSection":["Debates","DIC","Encuentros","Exposiciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/","name":"En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","isPartOf":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/#primaryimage"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?fit=1280%2C875&ssl=1","datePublished":"2022-12-01T12:47:28+00:00","dateModified":"2022-12-01T12:48:38+00:00","breadcrumb":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/#primaryimage","url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?fit=1280%2C875&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?fit=1280%2C875&ssl=1","width":1280,"height":875},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/en-cochabamba-carta-modelo-de-peticion-de-acceso-a-informacion-gira-en-torno-a-salud-el-tren-metropolitano-y-la-felcn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/"},{"@type":"ListItem","position":2,"name":"En Cochabamba, carta modelo de petici\u00f3n de acceso a informaci\u00f3n gira en torno a salud, el Tren Metropolitano y la FELCN"}]},{"@type":"WebSite","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#website","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/","name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","description":"Reflexionar a la opini\u00f3n p\u00fablica sobre la aprobaci\u00f3n de la Ley de Acceso a la Informaci\u00f3n","publisher":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization","name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/07\/logo-DIC.png?fit=656%2C330&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/07\/logo-DIC.png?fit=656%2C330&ssl=1","width":656,"height":330,"caption":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/","https:\/\/x.com\/Fperiodismo"]},{"@type":"Person","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/person\/76866a0a8716e14bd4a78088e79c55ac","name":"Tania Frank","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g","caption":"Tania Frank"},"url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/author\/tania\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2022-11-28-at-17.15.32.jpeg?fit=1280%2C875&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/comments?post=11550"}],"version-history":[{"count":0,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/media\/11553"}],"wp:attachment":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/media?parent=11550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/categories?post=11550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/tags?post=11550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}