{"id":11775,"date":"2023-09-13T16:45:41","date_gmt":"2023-09-13T16:45:41","guid":{"rendered":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/?p=11775"},"modified":"2023-09-28T13:59:49","modified_gmt":"2023-09-28T13:59:49","slug":"11775-2","status":"publish","type":"post","link":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/","title":{"rendered":"Poder DIC, una llamada a la reflexi\u00f3n sobre el periodismo de investigaci\u00f3n en Bolivia"},"content":{"rendered":"<body><p><\/p>\n<div class=\"entry-header\">\n<h2 class=\"jeg_post_subtitle\">Los periodistas de investigaci\u00f3n Nelfy Fern\u00e1ndez y Carlos Quisberth hablaron de la necesidad de tener una ley de acceso a la informaci\u00f3n en el pa\u00eds<\/h2>\n<\/div>\n<div class=\"jeg_featured featured_image \">\n<div class=\"thumbnail-container\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"attachment-jnews-1140x570 size-jnews-1140x570 wp-post-image\" src=\"https:\/\/i0.wp.com\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Destacada.jpg?resize=696%2C379&#038;ssl=1\" sizes=\"auto, (max-width: 943px) 100vw, 943px\" srcset=\"https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Destacada.jpg 943w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Destacada-300x164.jpg 300w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Destacada-768x419.jpg 768w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Destacada-600x327.jpg 600w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Destacada-150x82.jpg 150w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Destacada-750x409.jpg 750w\" alt=\"\" width=\"696\" height=\"379\" loading=\"lazy\"><\/div>\n<\/div>\n<div class=\"jeg_share_top_container\"><\/div>\n<div class=\"jeg_ad jeg_article jnews_content_top_ads \">\n<div class=\"ads-wrapper \"><a href=\"https:\/\/verdadcontinta.com\/2023\/09\/13\/poder-dic-una-llamada-a-la-reflexion-sobre-el-periodismo-de-investigacion-en-bolivia\/\">Por Pablo Mustaff\u00e1<\/a><\/div>\n<\/div>\n<div class=\"entry-content with-share\">\n<div class=\"jeg_share_button share-float jeg_sticky_share clearfix share-monocrhome\">\n<div class=\"jegStickyHolder\">\n<div class=\"theiaStickySidebar\">\n<div class=\"jeg_share_float_container\">\n<div class=\"jeg_sharelist\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content-inner \">\n<p>Un nuevo cap\u00edtulo de <a href=\"https:\/\/verdadcontinta.com\/2023\/09\/02\/la-fundacion-para-el-periodismo-inicia-nuevo-ciclo-de-programas-sobre-derecho-a-la-informacion-y-la-comunicacion\/\" target=\"_blank\" rel=\"noopener\">Poder DIC<\/a> \u2014Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\u2014 se estren\u00f3 la ma\u00f1ana del martes 12 de septiembre con transmisiones simult\u00e1neas, tanto en Facebook Live como en Zoom, el programa de la <strong><a href=\"https:\/\/fundacionperiodismo.org\/\" target=\"_blank\" rel=\"noopener\">Fundaci\u00f3n para el Periodismo<\/a> y la Unesco lanz\u00f3 este segundo cap\u00edtulo con los periodistas de investigaci\u00f3n Nelfi Fern\u00e1ndez Reyes y Carlos Quisberth Fern\u00e1ndez como invitados<\/strong>.<\/p>\n<p><strong>La consigna de \u201cperiodismo de investigaci\u00f3n y acceso a la informaci\u00f3n p\u00fablica\u201d fue la que gui\u00f3 el desarrollo de la charla<\/strong> entre los invitados y el conductor Jes\u00fas Vargas Villena.<\/p>\n<p>Dadas las trayectorias y experiencias de los periodistas, se abord\u00f3 la tem\u00e1tica desde una mirada cr\u00edtica que dej\u00f3 como conclusi\u00f3n que en Bolivia a\u00fan falta normativa y cumplimiento de ella para hacer del periodismo de investigaci\u00f3n una labor factible.<\/p>\n<p>Carlos Quisberth, quien entre sus experiencias tiene el haber sido aprehendido durante un trabajo de investigaci\u00f3n, resalt\u00f3 las dificultades del periodismo investigativo en el pa\u00eds. Seg\u00fan apunta, <strong>el dif\u00edcil acceso a la informaci\u00f3n es uno de los motivos por los que el tiempo medio para realizar un trabajo se alarga semanas<\/strong>. Desde su punto de vista, complicaciones como esa, sumada a las bajas remuneraciones por el trabajo de investigaci\u00f3n, son las que sofocan a los periodistas.<\/p>\n<p>Para ver el programa haz <a href=\"https:\/\/fb.watch\/n0K_TLTFzw\/\" target=\"_blank\" rel=\"noopener\">click aqu\u00ed<\/a>.<\/p>\n<p>Nelfi Fern\u00e1ndez se refiri\u00f3 al ejemplo de pa\u00edses cuyos funcionarios p\u00fablicos por medio de las normativas, tienen la obligaci\u00f3n de compartir la informaci\u00f3n y datos solicitados por periodistas.<strong> Explica que, en el caso de Bolivia, cuando se solicita informaci\u00f3n a entidades p\u00fablicas, los procesos para conseguirla no solo son complejos, sino que \u00abmuchas veces no llegan a nada\u00bb.<\/strong> Es por ello que la periodista aconseja a sus colegas buscar informaci\u00f3n de todas la formas posibles y llevar una sistematizaci\u00f3n que respalde el trabajo.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-full wp-image-12431\" src=\"https:\/\/i0.wp.com\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Carlos-Quisberth.jpg?resize=696%2C374&#038;ssl=1\" sizes=\"auto, (max-width: 941px) 100vw, 941px\" srcset=\"https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Carlos-Quisberth.jpg 941w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Carlos-Quisberth-300x161.jpg 300w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Carlos-Quisberth-768x412.jpg 768w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Carlos-Quisberth-600x322.jpg 600w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Carlos-Quisberth-150x80.jpg 150w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Carlos-Quisberth-750x402.jpg 750w\" alt=\"\" width=\"696\" height=\"374\" data-pin-no-hover=\"true\" loading=\"lazy\"><\/p>\n<p>Otro de los temas sobre los que conversaron los invitados fue el uso de audios filtrados como fuente, caso en el que aconsejan ante todo la verificaci\u00f3n del origen del material. Adem\u00e1s, <strong>hubo una menci\u00f3n a los enfoques que tienen actualmente las carreras de Comunicaci\u00f3n en Bolivia y al hecho de que los estudiantes poco a poco pierden el inter\u00e9s en la labor period\u00edstica, adem\u00e1s que las mallas curriculares no est\u00e1n ahondando en el campo de la investigaci\u00f3n.\u00a0<\/strong><\/p>\n<p><strong>Poder DIC tiene dos transmisiones mensuales y el acceso a todas las charlas es gratuito<\/strong>. Para ser parte se debe llenar un formulario de registro que la Fundaci\u00f3n para el Periodismo comparte en su p\u00e1gina web los d\u00edas previos a la charla o sumarse a la transmisi\u00f3n por Facebook Live.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-full wp-image-12430\" src=\"https:\/\/i0.wp.com\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Nelfi-Fernandez.jpg?resize=696%2C373&#038;ssl=1\" sizes=\"auto, (max-width: 945px) 100vw, 945px\" srcset=\"https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Nelfi-Fernandez.jpg 945w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Nelfi-Fernandez-300x161.jpg 300w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Nelfi-Fernandez-768x411.jpg 768w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Nelfi-Fernandez-600x321.jpg 600w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Nelfi-Fernandez-150x80.jpg 150w, https:\/\/verdadcontinta.com\/wp-content\/uploads\/2023\/09\/Nelfi-Fernandez-750x402.jpg 750w\" alt=\"\" width=\"696\" height=\"373\" data-pin-no-hover=\"true\" loading=\"lazy\"><\/p>\n<h2>De los invitados<\/h2>\n<p>Nelfy Fern\u00e1ndez es una periodista especializada en cobertura de crimen organizado, periodista digital y de investigaci\u00f3n. Fue nominada a los Data Journalism Awards y al premio Gabriel Gabriel Garc\u00eda M\u00e1rquez en 2016 por su investigaci\u00f3n <a href=\"https:\/\/data.eldeber.com.bo\/seccion\/gabinete\/\"><em>El patrimonio del Gabinete de Evo<\/em><\/a>. En 2019 fue galardonada con el premio Excelencia en Periodismo de Chile por la investigaci\u00f3n <a href=\"https:\/\/www.connectas.org\/especiales\/carne-de-canon\/\"><em>Las mujeres carnes del ca\u00f1\u00f3n del narcotr\u00e1fico<\/em><\/a>. En 2021 fue finalista del premio Gabo con la investigaci\u00f3n colaborativa transnacional <a href=\"https:\/\/tierraderesistentes.com\/es\/\"><em>Tierra de resistentes<\/em><\/a>. Es miembro del Consorcio Internacional de Periodistas de Investigaci\u00f3n (ICIJ) y del Connectas Hub. Trabaja en el diario El Deber en Santa Cruz, medio en el que dirigi\u00f3 varias investigaciones; entre ellas, <em><a href=\"https:\/\/data.eldeber.com.bo\/seccion\/panamapapers\/\">The Panama Papers<\/a> -Cap\u00edtulo de Bolivia-<\/em> y <a href=\"https:\/\/eldeber.com.bo\/bbc\/fincen-files-la-filtracion-de-miles-de-reportes-bancarios-que-expone-el-lavado-_201255\"><em>FinCen Files<\/em><\/a>.<\/p>\n<p>Carlos Quisbert es fotoperiodista y periodista de investigaci\u00f3n en el \u00e1rea de seguridad, quien trabaj\u00f3 en El Diario y P\u00e1gina Siete en La Paz. Es corresponsal militar graduado en la Escuela de C\u00f3ndores de Sanandita. Obtuvo el premio nacional de periodismo por la <a href=\"https:\/\/www.eldiario.net\/portal\/2023\/04\/21\/justicia-impide-que-la-victima-sea-parte-del-proceso-contra-pacajes\/\">investigaci\u00f3n<\/a> del caso del beb\u00e9 Alexander y el audio de la jueza Patricia Pacajes, reportaje que dio lugar a la libertad del m\u00e9dico Jhiery Fern\u00e1ndez.<\/p>\n<p>Tambi\u00e9n resalta por su <a href=\"https:\/\/www.paginasiete.bo\/especial01\/davila-el-coronel-que-es-acusado-de-narco-por-la-dea-y-que-incomoda-a-evo-MI5846806\">investigaci\u00f3n<\/a> y seguimiento al caso del exjefe policial Maximiliano D\u00e1vila P\u00e9rez, quien fue vinculado con el narcotr\u00e1fico.<\/p>\n<h2>Poder DIC<\/h2>\n<p>Poder DIC naci\u00f3 el a\u00f1o 2022 con un ciclo de 16 transmisiones conducidas por la periodista Patricia Cusicanqui Hanssen.<\/p>\n<p>Desde septiembre de 2023 Poder DIC se abri\u00f3 a un nuevo ciclo con dos transmisiones mensuales<\/p>\n<p>Este 28 de septiembre se recuerda el <strong>D\u00eda Internacional del Acceso Universal a la Informaci\u00f3n<\/strong>, reconocido desde el 2016 gracias a una Conferencia General de la Organizaci\u00f3n de las Naciones Unidas para la Educaci\u00f3n, la Ciencia y la Cultura (Unesco), fecha en la cual Poder DIC tendr\u00e1 una transmisi\u00f3n especial.<\/p>\n<\/div>\n<\/div>\n<p><\/p>\n<\/body>","protected":false},"excerpt":{"rendered":"<p>Los periodistas de investigaci\u00f3n Nelfy Fern\u00e1ndez y Carlos Quisberth hablaron de la necesidad de tener una ley de acceso a la informaci\u00f3n en el pa\u00eds Por Pablo Mustaff\u00e1 Un nuevo cap\u00edtulo de Poder DIC \u2014Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\u2014 se estren\u00f3 la ma\u00f1ana del martes 12 de septiembre con transmisiones simult\u00e1neas, tanto en Facebook [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11776,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[62],"tags":[],"class_list":["post-11775","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nota-de-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Poder DIC, una llamada a la reflexi\u00f3n sobre el periodismo de investigaci\u00f3n en Bolivia - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poder DIC, una llamada a la reflexi\u00f3n sobre el periodismo de investigaci\u00f3n en Bolivia - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Los periodistas de investigaci\u00f3n Nelfy Fern\u00e1ndez y Carlos Quisberth hablaron de la necesidad de tener una ley de acceso a la informaci\u00f3n en el pa\u00eds Por Pablo Mustaff\u00e1 Un nuevo cap\u00edtulo de Poder DIC \u2014Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\u2014 se estren\u00f3 la ma\u00f1ana del martes 12 de septiembre con transmisiones simult\u00e1neas, tanto en Facebook [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-13T16:45:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-28T13:59:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/09\/Destacada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"943\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tania Frank\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Fperiodismo\" \/>\n<meta name=\"twitter:site\" content=\"@Fperiodismo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tania Frank\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/11775-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/11775-2\\\/\"},\"author\":{\"name\":\"Tania Frank\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/person\\\/76866a0a8716e14bd4a78088e79c55ac\"},\"headline\":\"Poder DIC, una llamada a la reflexi\u00f3n sobre el periodismo de investigaci\u00f3n en Bolivia\",\"datePublished\":\"2023-09-13T16:45:41+00:00\",\"dateModified\":\"2023-09-28T13:59:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/11775-2\\\/\"},\"wordCount\":835,\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/11775-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Destacada.jpg?fit=943%2C514&ssl=1\",\"articleSection\":[\"Nota de Prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/11775-2\\\/\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/11775-2\\\/\",\"name\":\"Poder DIC, una llamada a la reflexi\u00f3n sobre el periodismo de investigaci\u00f3n en Bolivia - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/11775-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/11775-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Destacada.jpg?fit=943%2C514&ssl=1\",\"datePublished\":\"2023-09-13T16:45:41+00:00\",\"dateModified\":\"2023-09-28T13:59:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/11775-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/11775-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/11775-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Destacada.jpg?fit=943%2C514&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Destacada.jpg?fit=943%2C514&ssl=1\",\"width\":943,\"height\":514},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/11775-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Poder DIC, una llamada a la reflexi\u00f3n sobre el periodismo de investigaci\u00f3n en Bolivia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#website\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\",\"name\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"description\":\"Reflexionar a la opini\u00f3n p\u00fablica sobre la aprobaci\u00f3n de la Ley de Acceso a la Informaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\",\"name\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-DIC.png?fit=656%2C330&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-DIC.png?fit=656%2C330&ssl=1\",\"width\":656,\"height\":330,\"caption\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FundacionParaelPeriodismo\\\/\",\"https:\\\/\\\/x.com\\\/Fperiodismo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/person\\\/76866a0a8716e14bd4a78088e79c55ac\",\"name\":\"Tania Frank\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g\",\"caption\":\"Tania Frank\"},\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/author\\\/tania\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Poder DIC, una llamada a la reflexi\u00f3n sobre el periodismo de investigaci\u00f3n en Bolivia - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/","og_locale":"es_ES","og_type":"article","og_title":"Poder DIC, una llamada a la reflexi\u00f3n sobre el periodismo de investigaci\u00f3n en Bolivia - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","og_description":"Los periodistas de investigaci\u00f3n Nelfy Fern\u00e1ndez y Carlos Quisberth hablaron de la necesidad de tener una ley de acceso a la informaci\u00f3n en el pa\u00eds Por Pablo Mustaff\u00e1 Un nuevo cap\u00edtulo de Poder DIC \u2014Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\u2014 se estren\u00f3 la ma\u00f1ana del martes 12 de septiembre con transmisiones simult\u00e1neas, tanto en Facebook [&hellip;]","og_url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/","og_site_name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/","article_published_time":"2023-09-13T16:45:41+00:00","article_modified_time":"2023-09-28T13:59:49+00:00","og_image":[{"width":943,"height":514,"url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/09\/Destacada.jpg","type":"image\/jpeg"}],"author":"Tania Frank","twitter_card":"summary_large_image","twitter_creator":"@Fperiodismo","twitter_site":"@Fperiodismo","twitter_misc":{"Escrito por":"Tania Frank","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/#article","isPartOf":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/"},"author":{"name":"Tania Frank","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/person\/76866a0a8716e14bd4a78088e79c55ac"},"headline":"Poder DIC, una llamada a la reflexi\u00f3n sobre el periodismo de investigaci\u00f3n en Bolivia","datePublished":"2023-09-13T16:45:41+00:00","dateModified":"2023-09-28T13:59:49+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/"},"wordCount":835,"publisher":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/09\/Destacada.jpg?fit=943%2C514&ssl=1","articleSection":["Nota de Prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/","name":"Poder DIC, una llamada a la reflexi\u00f3n sobre el periodismo de investigaci\u00f3n en Bolivia - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","isPartOf":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/#primaryimage"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/09\/Destacada.jpg?fit=943%2C514&ssl=1","datePublished":"2023-09-13T16:45:41+00:00","dateModified":"2023-09-28T13:59:49+00:00","breadcrumb":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/#primaryimage","url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/09\/Destacada.jpg?fit=943%2C514&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/09\/Destacada.jpg?fit=943%2C514&ssl=1","width":943,"height":514},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/11775-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/"},{"@type":"ListItem","position":2,"name":"Poder DIC, una llamada a la reflexi\u00f3n sobre el periodismo de investigaci\u00f3n en Bolivia"}]},{"@type":"WebSite","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#website","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/","name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","description":"Reflexionar a la opini\u00f3n p\u00fablica sobre la aprobaci\u00f3n de la Ley de Acceso a la Informaci\u00f3n","publisher":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization","name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/07\/logo-DIC.png?fit=656%2C330&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/07\/logo-DIC.png?fit=656%2C330&ssl=1","width":656,"height":330,"caption":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/","https:\/\/x.com\/Fperiodismo"]},{"@type":"Person","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/person\/76866a0a8716e14bd4a78088e79c55ac","name":"Tania Frank","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g","caption":"Tania Frank"},"url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/author\/tania\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/09\/Destacada.jpg?fit=943%2C514&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/comments?post=11775"}],"version-history":[{"count":3,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11775\/revisions"}],"predecessor-version":[{"id":11800,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11775\/revisions\/11800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/media\/11776"}],"wp:attachment":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/media?parent=11775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/categories?post=11775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/tags?post=11775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}