{"id":11806,"date":"2023-10-17T19:01:04","date_gmt":"2023-10-17T19:01:04","guid":{"rendered":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/?p=11806"},"modified":"2023-10-12T19:03:46","modified_gmt":"2023-10-12T19:03:46","slug":"el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental","status":"publish","type":"post","link":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/","title":{"rendered":"El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental."},"content":{"rendered":"<body><p><\/p><em>El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental. El Gobierno dice que se cumple, pero tres expertas en el tema lo niegan.<\/em>\n<h5><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-full wp-image-78939\" src=\"https:\/\/i0.wp.com\/boliviaverifica.bo\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-12-at-01.00.02.jpeg?resize=696%2C392&#038;ssl=1\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" srcset=\"https:\/\/boliviaverifica.bo\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-12-at-01.00.02.jpeg 1600w, https:\/\/boliviaverifica.bo\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-12-at-01.00.02-300x169.jpeg 300w, https:\/\/boliviaverifica.bo\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-12-at-01.00.02-768x432.jpeg 768w, https:\/\/boliviaverifica.bo\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-12-at-01.00.02-1024x576.jpeg 1024w\" alt=\"\" width=\"696\" height=\"392\" loading=\"lazy\">En septiembre de 2018, 14 pa\u00edses de Am\u00e9rica Latina y el Caribe fueron los primeros en firmar el Acuerdo de Escaz\u00fa.<\/h5>\n<p>\u00a0<\/p>\n<p>El Acuerdo Regional sobre Acceso a la Informaci\u00f3n, Participaci\u00f3n P\u00fablica y Acceso a la Justicia en Asuntos Ambientales en Am\u00e9rica Latina y El Caribe, conocido como\u00a0<a href=\"https:\/\/www.cepal.org\/es\/acuerdodeescazu\">Acuerdo de Escaz\u00fa<\/a>, entr\u00f3 en vigor en Bolivia y en otros 11 pa\u00edses que lo ratificaron el 22 de abril de 2021.<\/p>\n<p>Desde este hecho hist\u00f3rico, los habitantes de toda \u00e1rea afectada por proyectos extractivistas, los defensores de los derechos del medio ambiente, los periodistas y la ciudadan\u00eda en general en Bolivia tienen, seg\u00fan la norma, el derecho de acceder a la informaci\u00f3n p\u00fablica y a la justicia ambiental y a tomar decisiones informadas en esta materia.<\/p>\n<p>Sin embargo, el acuerdo y, en general, la normativa ambiental en Bolivia no se cumple. As\u00ed lo afirmaron una especialista en gesti\u00f3n ambiental, una activista y una periodista durante un conversatorio organizado por Poder DIC (Derecho a la Informaci\u00f3n y la Comunicaci\u00f3n), un programa de la Fundaci\u00f3n para el Periodismo (FPP).<\/p>\n<p>Por su parte, el Gobierno, a trav\u00e9s del viceministro de Medio Ambiente, Biodiversidad, Cambios Clim\u00e1ticos y de Gesti\u00f3n y Desarrollo Forestal, Mag\u00edn Herrera, asegur\u00f3 esta semana en se cumple con la ley, lo que incluye con el acuerdo de Escaz\u00fa.<\/p>\n<p><strong>\u00a0<\/strong><strong>Qu\u00e9 dicen los actores involucrados en la tem\u00e1tica<\/strong><\/p>\n<p>La exdirectora de la Liga de Defensa del Medio Ambiente (Lidema), Jenny Gruenberger, explic\u00f3 a Poder DIC que el acceso a la informaci\u00f3n es limitado y que no hay respuesta a las solicitudes dentro los \u00f3rganos del Estado. \u201cPor ejemplo el pa\u00eds tiene que elaborar un informe sobre el estado ambiental cada cuatro a\u00f1os y nunca lo ha hecho. Este problema no tiene nada que ver con el MAS o con la oposici\u00f3n. Hist\u00f3ricamente nunca se ha hecho. Esto demuestra la poca importancia que se le da a este tema en Bolivia\u201d, dijo.<\/p>\n<p>Gruenberger afirm\u00f3 que la poca colaboraci\u00f3n de los gobiernos para acceder a la informaci\u00f3n, no viene de ahora, sino de siempre. Ahora, obtener informaci\u00f3n de los sectores estrat\u00e9gicos, como hidrocarburos, es mucho m\u00e1s dif\u00edcil, incluso ocultan informaci\u00f3n.<\/p>\n<p>Mercedes Villarroel, abogada especializada en gesti\u00f3n estrat\u00e9gica ambiental de Lidema, record\u00f3 que el Acuerdo de Escaz\u00fa es un instrumento que tienen los pa\u00edses de Am\u00e9rica Latina y el Caribe acceder a tres importantes derechos relacionados con la tem\u00e1tica ambiental.<\/p>\n<p>\u201cSon el derecho a la informaci\u00f3n, el derecho de acceso a la participaci\u00f3n y el derecho de acceso a la justicia, pero, adem\u00e1s, el Acuerdo de Escaz\u00fa implementa un cuarto componente que habla sobre la defensa de los defensores medioambientales\u201d, expuso.<\/p>\n<p>Villarroel se\u00f1al\u00f3 que, en cuanto al derecho al acceso a informaci\u00f3n, el Acuerdo establece que todas las partes tienen derecho a acceder a la informaci\u00f3n p\u00fablica relacionada a la tem\u00e1tica medioambiental y los Estados tienen la obligaci\u00f3n de otorgarla.<\/p>\n<p>\u201cEs el derecho de la ciudadan\u00eda a acceder a toda informaci\u00f3n p\u00fablica que genera el pa\u00eds. Por ejemplo, si hay contratos de actividades, obras o proyectos que se adjudican o se pretendan ejecutar dentro del territorio, el Estado tiene la obligaci\u00f3n de hacerlos p\u00fablicos. Es el caso de las actividades mineras y otras que tienen que ver con la extracci\u00f3n de recursos naturales renovables o no renovables y que pueden generar un impacto negativo en nuestro medio ambiente\u201d, dijo.<\/p>\n<p>Agreg\u00f3 que, seg\u00fan el Acuerdo, la ciudadan\u00eda boliviana tambi\u00e9n tiene derecho a participar de manera informada en la toma de decisiones. \u201cEn este caso, el derecho de acceso a la informaci\u00f3n est\u00e1 relacionado con la consulta previa y la informaci\u00f3n previa que se debe dar a las comunidades para la participaci\u00f3n activa en estos temas\u201d, apunt\u00f3.<\/p>\n<h5><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-full wp-image-78944\" src=\"https:\/\/i0.wp.com\/boliviaverifica.bo\/wp-content\/uploads\/2023\/10\/acuerdo-escazu-unicef.jpg?resize=696%2C309&#038;ssl=1\" sizes=\"auto, (max-width: 1602px) 100vw, 1602px\" srcset=\"https:\/\/boliviaverifica.bo\/wp-content\/uploads\/2023\/10\/acuerdo-escazu-unicef.jpg 1602w, https:\/\/boliviaverifica.bo\/wp-content\/uploads\/2023\/10\/acuerdo-escazu-unicef-300x133.jpg 300w, https:\/\/boliviaverifica.bo\/wp-content\/uploads\/2023\/10\/acuerdo-escazu-unicef-768x341.jpg 768w, https:\/\/boliviaverifica.bo\/wp-content\/uploads\/2023\/10\/acuerdo-escazu-unicef-1024x455.jpg 1024w\" alt=\"\" width=\"696\" height=\"309\" loading=\"lazy\">Organismos de la ONU, como Unicef,<a href=\"https:\/\/www.unicef.org\/lac\/informes\/acuerdo-escazu-para-jovenes\">\u00a0socializan el Acuerdo<\/a>\u00a0con enfoque en la juventud.<\/h5>\n<p>\u00a0<\/p>\n<p><strong>\u00bfQu\u00e9 sucede con las solicitudes de los medios y la prensa?<\/strong><\/p>\n<p>La periodista Roc\u00edo Lloret, directora de la revista La Regi\u00f3n, especializada en temas medioambientales y turismo sostenible, asegur\u00f3 a Poder DIC que el Acuerdo de Escaz\u00fa no se cumple en el pa\u00eds.<\/p>\n<p>\u201cBolivia es uno de los pa\u00edses con mejor normativa en temas medioambientales. Lamentablemente, solo es letra muerta. En los hechos, como periodistas y en general para la ciudadan\u00eda hay trabas\u201d.<\/p>\n<p>A\u00f1adi\u00f3 que, si para los periodistas es dif\u00edcil acceder a informaci\u00f3n sobre los proyectos que pueden afectar el medio ambiente, es peor a\u00fan para el ciudadano com\u00fan.<\/p>\n<p>Lloret cit\u00f3 como ejemplos que es dif\u00edcil conocer qu\u00e9 empresa se adjudic\u00f3 un proyecto o qu\u00e9 tipo de empresa es la que quiere entrar a una comunidad en un \u00e1rea protegida para explotar oro u otro recurso natural.<\/p>\n<p>En cuanto a la consulta previa, apunto que, en muchos casos, no solo se limita la informaci\u00f3n a los pueblos ind\u00edgenas, sino que se les enga\u00f1a, ignorando su derecho sobre la tierra y el territorio.<\/p>\n<p>\u201cEl Ministerio de Medio Ambiente, las entidades p\u00fablicas, tendr\u00edan que verificar que la consulta se realice efectivamente, pero hay historias que revelan que se han firmado acuerdos incluso en medio de churrascos. Yo he documentado un caso de 2021, cuando les han dicho a los asistentes (ind\u00edgenas) que pongan sus nombres en una hoja y (los representantes de la empresa) han presentado eso para argumentar que todos estaban de acuerdo con que se construya una carretera\u201d, denunci\u00f3.<\/p>\n<p><strong>\u00a0<\/strong><strong>Qu\u00e9 argumenta el Gobierno nacional<\/strong><\/p>\n<p>El viceministro Herrera asegur\u00f3 que existe acceso transparente a la informaci\u00f3n del Gobierno en materia de medio ambiente. \u201cParticularmente, mi despacho no ejecuta proyectos, pero los responsables de la ejecuci\u00f3n deben entregar la informaci\u00f3n. Nosotros atendemos a la gente m\u00e1s all\u00e1 del horario de oficina\u201d, dijo.<\/p>\n<p>Record\u00f3 que mucha gente, lo busca, por ejemplo, para que se indague la explotaci\u00f3n presuntamente ilegal de oro en la Amazon\u00eda. Sin embargo, asegur\u00f3, este tema est\u00e1 en manos de la Autoridad Jurisdiccional Administrativa Minera (AJAM).<\/p>\n<p>\u201cHace poco tambi\u00e9n se dijo que hab\u00eda fallecidos por consumo de agua contaminada con mercurio cerca de los r\u00edos donde explotan oro. Sin embargo, un informe oficial rechaza esa versi\u00f3n y atribuye a otros problemas de salud el fallecimiento de dos personas\u201d, indic\u00f3.<\/p>\n<p><strong>\u00a0<\/strong><strong>Justicia medioambiental<\/strong><\/p>\n<p>As\u00ed como los entrevistados reclamaron porque no se cumple el acceso a la informaci\u00f3n medioambiental, tambi\u00e9n denunciaron fallas en la aplicaci\u00f3n de la justicia en esta \u00e1rea.<\/p>\n<p>\u201cSe incorpor\u00f3 en el sistema judicial del Estado los juzgados agroambientales, pero dentro de sus atribuciones no hemos podido incidir como sociedad civil para que estos cumplan con su misi\u00f3n como establece la ley (\u2026) Hay casos que no han tenido respuesta en los estratos judiciales\u201d, dijo Villarroel.<\/p>\n<p>La abogada llam\u00f3 tambi\u00e9n la atenci\u00f3n sobre los problemas derivados de la contraposici\u00f3n de unas leyes con otras. Por ejemplo, cit\u00f3 que la ley minera se apoya en la Constituci\u00f3n, la cual se\u00f1ala que todo recurso no renovable puede ser explotado si es de inter\u00e9s p\u00fablico. \u201cAs\u00ed, el Estado se atribuye un derecho prioritario sobre nuestros recursos naturales, por encima de los pueblos ind\u00edgenas. Esas falencias son brechas que debemos allanar\u201d, expuso.<\/p>\n<h3><strong>Consulta previa informada<\/strong><\/h3>\n<p>La consulta previa, como dice la misma Constituci\u00f3n, debe ser libre e informada, pero generalmente estas premisas no se cumplen.<\/p>\n<p>Lloret, que como periodista conoce casos de consultas realizadas en la Amazon\u00eda y la Chiquitan\u00eda, apunt\u00f3 que el gran problema es la falta de acceso a informaci\u00f3n transparente y oportuna desde el Estado.<\/p>\n<p>Las empresas que buscan entrar a explotar recursos naturales, indic\u00f3, suelen apelar directamente a las necesidades que tienen los pueblos ind\u00edgenas.<\/p>\n<p>\u201cMuchas de estas empresas llegan directamente (al lugar) con sus t\u00e9cnicos y le hablan a la gente en un lenguaje inentendible, ni siquiera para un periodista. Casi siempre mencionan que va a haber beneficios, pero cuando uno empieza a ver qu\u00e9 tipo de beneficios les ofrecen se da cuenta que est\u00e1n ofreciendo una escuelita de 20 mil d\u00f3lares, un coliseo, montos que parecieran elevados para su realidad, pero que en los hechos son \u00ednfimos\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Para Lloret, el problema no es la discusi\u00f3n sobre desarrollo, porque los propios pueblos dicen que s\u00ed quieren desarrollo y tienen derecho a beneficiarse de \u00e9l; \u201cel problema es la informaci\u00f3n tergiversada y muchas veces manipulada que reciben\u201d. De esta forma, dijo, terminan aceptando una compensaci\u00f3n m\u00ednima por proyectos que har\u00e1n mucho da\u00f1o a su h\u00e1bitat.<\/p>\n<p>\u201cEl tema no pasa porque se haga una lucha f\u00e9rrea para que nunca se explote nada, sino que se lo haga de manera responsable y sostenible. Por eso las propias leyes se\u00f1alan que se deben elaborar informes ambientales, informes de impacto, informes de mitigaci\u00f3n. Pero el tema es que no se cumple\u201d, lament\u00f3.<\/p>\n<\/body>","protected":false},"excerpt":{"rendered":"<p>El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental. El Gobierno dice que se cumple, pero tres expertas en el tema lo niegan. En septiembre de 2018, 14 pa\u00edses de Am\u00e9rica Latina y el [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11807,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[62],"tags":[],"class_list":["post-11806","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nota-de-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental. - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental. - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental. El Gobierno dice que se cumple, pero tres expertas en el tema lo niegan. En septiembre de 2018, 14 pa\u00edses de Am\u00e9rica Latina y el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/\" \/>\n<meta property=\"og:site_name\" content=\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-17T19:01:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-12-at-01.00.02.jpeg?fit=1280%2C720&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tania Frank\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Fperiodismo\" \/>\n<meta name=\"twitter:site\" content=\"@Fperiodismo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tania Frank\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\\\/\"},\"author\":{\"name\":\"Tania Frank\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/person\\\/76866a0a8716e14bd4a78088e79c55ac\"},\"headline\":\"El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental.\",\"datePublished\":\"2023-10-17T19:01:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\\\/\"},\"wordCount\":1603,\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/WhatsApp-Image-2023-10-12-at-01.00.02.jpeg?fit=1280%2C720&ssl=1\",\"articleSection\":[\"Nota de Prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\\\/\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\\\/\",\"name\":\"El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental. - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/WhatsApp-Image-2023-10-12-at-01.00.02.jpeg?fit=1280%2C720&ssl=1\",\"datePublished\":\"2023-10-17T19:01:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/WhatsApp-Image-2023-10-12-at-01.00.02.jpeg?fit=1280%2C720&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/WhatsApp-Image-2023-10-12-at-01.00.02.jpeg?fit=1280%2C720&ssl=1\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#website\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\",\"name\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"description\":\"Reflexionar a la opini\u00f3n p\u00fablica sobre la aprobaci\u00f3n de la Ley de Acceso a la Informaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\",\"name\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-DIC.png?fit=656%2C330&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-DIC.png?fit=656%2C330&ssl=1\",\"width\":656,\"height\":330,\"caption\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FundacionParaelPeriodismo\\\/\",\"https:\\\/\\\/x.com\\\/Fperiodismo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/person\\\/76866a0a8716e14bd4a78088e79c55ac\",\"name\":\"Tania Frank\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g\",\"caption\":\"Tania Frank\"},\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/author\\\/tania\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental. - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/","og_locale":"es_ES","og_type":"article","og_title":"El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental. - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","og_description":"El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental. El Gobierno dice que se cumple, pero tres expertas en el tema lo niegan. En septiembre de 2018, 14 pa\u00edses de Am\u00e9rica Latina y el [&hellip;]","og_url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/","og_site_name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/","article_published_time":"2023-10-17T19:01:04+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-12-at-01.00.02.jpeg?fit=1280%2C720&ssl=1","type":"image\/jpeg"}],"author":"Tania Frank","twitter_card":"summary_large_image","twitter_creator":"@Fperiodismo","twitter_site":"@Fperiodismo","twitter_misc":{"Escrito por":"Tania Frank","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/#article","isPartOf":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/"},"author":{"name":"Tania Frank","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/person\/76866a0a8716e14bd4a78088e79c55ac"},"headline":"El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental.","datePublished":"2023-10-17T19:01:04+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/"},"wordCount":1603,"publisher":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-12-at-01.00.02.jpeg?fit=1280%2C720&ssl=1","articleSection":["Nota de Prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/","name":"El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental. - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","isPartOf":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/#primaryimage"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-12-at-01.00.02.jpeg?fit=1280%2C720&ssl=1","datePublished":"2023-10-17T19:01:04+00:00","breadcrumb":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/#primaryimage","url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-12-at-01.00.02.jpeg?fit=1280%2C720&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-12-at-01.00.02.jpeg?fit=1280%2C720&ssl=1","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/el-acuerdo-de-escazu-busca-garantizar-el-acceso-a-la-informacion-la-participacion-de-la-ciudadania-en-la-toma-de-decisiones-y-el-acceso-a-la-justicia-en-materia-ambiental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/"},{"@type":"ListItem","position":2,"name":"El Acuerdo de Escaz\u00fa busca garantizar el acceso a la informaci\u00f3n, la participaci\u00f3n de la ciudadan\u00eda en la toma de decisiones y el acceso a la justicia en materia ambiental."}]},{"@type":"WebSite","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#website","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/","name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","description":"Reflexionar a la opini\u00f3n p\u00fablica sobre la aprobaci\u00f3n de la Ley de Acceso a la Informaci\u00f3n","publisher":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization","name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/07\/logo-DIC.png?fit=656%2C330&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/07\/logo-DIC.png?fit=656%2C330&ssl=1","width":656,"height":330,"caption":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/","https:\/\/x.com\/Fperiodismo"]},{"@type":"Person","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/person\/76866a0a8716e14bd4a78088e79c55ac","name":"Tania Frank","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81b79fc40ab736a5478717e6c1824bde5c90d8beb1dbd0e433e5a29ee9d126fa?s=96&d=mm&r=g","caption":"Tania Frank"},"url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/author\/tania\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-12-at-01.00.02.jpeg?fit=1280%2C720&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/comments?post=11806"}],"version-history":[{"count":1,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11806\/revisions"}],"predecessor-version":[{"id":11808,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11806\/revisions\/11808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/media\/11807"}],"wp:attachment":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/media?parent=11806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/categories?post=11806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/tags?post=11806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}