{"id":11815,"date":"2023-11-10T18:41:46","date_gmt":"2023-11-10T18:41:46","guid":{"rendered":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/?p=11815"},"modified":"2023-11-10T18:41:46","modified_gmt":"2023-11-10T18:41:46","slug":"acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social","status":"publish","type":"post","link":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/","title":{"rendered":"Acceder a la informaci\u00f3n p\u00fablica es una condici\u00f3n indispensable para ejercer la participaci\u00f3n y el control social"},"content":{"rendered":"<body><p><\/p><strong><em>Dos expertos explican los alcances de este derecho de la sociedad civil organizada y la importancia que tiene para ello la transparencia en la gesti\u00f3n de las entidades estatales.<\/em><\/strong>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-full wp-image-80038\" src=\"https:\/\/i0.wp.com\/boliviaverifica.bo\/wp-content\/uploads\/2023\/11\/Control-social.webp?resize=696%2C349&#038;ssl=1\" sizes=\"auto, (max-width: 922px) 100vw, 922px\" srcset=\"https:\/\/boliviaverifica.bo\/wp-content\/uploads\/2023\/11\/Control-social.webp 922w, https:\/\/boliviaverifica.bo\/wp-content\/uploads\/2023\/11\/Control-social-300x150.webp 300w, https:\/\/boliviaverifica.bo\/wp-content\/uploads\/2023\/11\/Control-social-768x385.webp 768w\" alt=\"\" width=\"696\" height=\"349\" loading=\"lazy\"><\/p>\n<p>La participaci\u00f3n y control social, una prerrogativa de la ciudadan\u00eda establecida tanto por la Constituci\u00f3n Pol\u00edtica del Estado (CPE) como por ley espec\u00edfica, solo puede ser posible si la sociedad civil organizada accede a la informaci\u00f3n p\u00fablica.<\/p>\n<p>El art\u00edculo\u00a0<a href=\"http:\/\/www.planificacion.gob.bo\/uploads\/marco-legal\/nueva_constitucion_politica_del_estado.pdf\">241 de la Carta Magna<\/a>, referido a la participaci\u00f3n y el control social, reconoce que la poblaci\u00f3n puede participar \u201cen el dise\u00f1o de las pol\u00edticas p\u00fablicas\u201d, en el \u201ccontrol a la gesti\u00f3n p\u00fablica\u201d y en el control \u201cde la calidad de los servicios p\u00fablicos\u201d.<\/p>\n<p>En tanto que el\u00a0<a href=\"http:\/\/www.planificacion.gob.bo\/uploads\/marco-legal\/nueva_constitucion_politica_del_estado.pdf\">art\u00edculo 242<\/a>\u00a0detalla los alcances y condiciones para el ejercicio de esta facultad:<\/p>\n<p>1. Participar en la formulaci\u00f3n de las pol\u00edticas de Estado.<\/p>\n<p>2. Apoyar al \u00d3rgano Legislativo en la construcci\u00f3n colectiva de las leyes.<\/p>\n<p>3. Desarrollar el control social en todos los niveles del gobierno y las entidades territoriales aut\u00f3nomas, aut\u00e1rquicas, descentralizadas y desconcentradas.<\/p>\n<p>4.\u00a0<strong>Generar un manejo transparente de la informaci\u00f3n y del uso de los recursos<\/strong>\u00a0en todos los espacios de la gesti\u00f3n p\u00fablica. La\u00a0<strong>informaci\u00f3n solicitada por el control social no podr\u00e1 denegarse<\/strong>, y ser\u00e1 entregada de manera completa, veraz, adecuada y oportuna.<\/p>\n<p>5. Formular informes que fundamenten la solicitud de la revocatoria de mandato, de acuerdo al procedimiento establecido en la Constituci\u00f3n y la ley.<\/p>\n<p>6. Conocer y pronunciarse sobre los informes de gesti\u00f3n de los \u00f3rganos y funciones del Estado.<\/p>\n<p>7. Coordinar la planificaci\u00f3n y control con los \u00f3rganos y funciones del Estado.<\/p>\n<p>8. Denunciar ante las instituciones correspondientes para la investigaci\u00f3n y procesamiento, en los casos que se considere conveniente.<\/p>\n<p>9. Colaborar en los procedimientos de observaci\u00f3n p\u00fablica para la designaci\u00f3n de los cargos que correspondan.<\/p>\n<p>10. Apoyar al \u00f3rgano electoral en transparentar las postulaciones de los candidatos para los cargos p\u00fablicos que correspondan.<\/p>\n<p>El constitucionalista Julio Veizaga hizo \u00e9nfasis en los contenidos de lo que establece el numeral 4, pues para el ejercicio pleno de esta atribuci\u00f3n, la sociedad civil debe acceder a datos p\u00fablicos, lo que\u00a0<strong>le permitir\u00e1 tomar decisiones informadas<\/strong>.<\/p>\n<p>El investigador y capacitador responsable de la Fundaci\u00f3n Milenio, Herbet Irahola, quien convers\u00f3 sobre el tema en\u00a0<em>Poder DIC \u2013 Derecho a la Informaci\u00f3n y la Comunicaci\u00f3n<\/em>, record\u00f3 que el control social a la gesti\u00f3n p\u00fablica\u00a0<strong>se aplica en todos los niveles del Ejecutivo<\/strong>, as\u00ed como a las empresas p\u00fablicas, mixtas y privadas que administran recursos p\u00fablicos.<\/p>\n<p>Los otros \u00f3rganos del Estado y sus instituciones, es decir\u00a0<strong>el Legislativo, el Judicial y el Electoral<\/strong>, tambi\u00e9n deben someterse al control social. De igual manera el\u00a0<strong>Ministerio P\u00fablico<\/strong>, la\u00a0<strong>Defensor\u00eda<\/strong>\u00a0del Pueblo, la\u00a0<strong>Contralor\u00eda<\/strong>\u00a0General del Estado, la\u00a0<strong>Procuradur\u00eda<\/strong>, las\u00a0<strong>Fuerzas Armadas<\/strong>\u00a0y la\u00a0<strong>Polic\u00eda<\/strong>,\u00a0dijo Irahola en la charla con el programa producido por la Fundaci\u00f3n para el Periodismo (FPP).<\/p>\n<p>Seg\u00fan el experto, el objetivo es que la sociedad se sienta m\u00e1s cerca de la gesti\u00f3n p\u00fablica, dado que el control social se puede ejercer\u00a0<strong>desde la planificaci\u00f3n<\/strong>\u00a0de las pol\u00edticas p\u00fablicas y proyectos a ser ejecutados por las entidades estatales.<\/p>\n<p>\u201cNos acordamos del control social cuando hemos conocido de un acto de corrupci\u00f3n, una malversaci\u00f3n o cuando una obra se vino abajo\u201d, indic\u00f3. \u201cAh\u00ed reci\u00e9n la gente se pregunta \u2018\u00bfqu\u00e9 ha pasado?\u2019. La mayor\u00eda no se acuerda que el control social y la participaci\u00f3n vienen desde el proceso de la planificaci\u00f3n\u201d.<\/p>\n<h3>Qu\u00e9 dice la Ley 341 de Participaci\u00f3n y Control Social<\/h3>\n<p><a href=\"https:\/\/observatorioplanificacion.cepal.org\/sites\/default\/files\/instrument\/files\/LEY%20341.pdf\">La norma establece<\/a>\u00a0que el control social es un derecho constitucional mediante el cual todo actor social supervisar\u00e1 y evaluar\u00e1 la ejecuci\u00f3n de la gesti\u00f3n estatal, el manejo apropiado de los recursos econ\u00f3micos, materiales, humanos, naturales y la calidad de los servicios p\u00fablicos y servicios b\u00e1sicos, para la autorregulaci\u00f3n del orden social.<\/p>\n<p>Entre sus finalidades est\u00e1 el fortalecer la democracia participativa, representativa y comunitaria y transparentar la gesti\u00f3n p\u00fablica y el apropiado manejo de los recursos p\u00fablicos.<\/p>\n<p>Con ese fin, plantea entre sus principios esenciales la\u00a0<strong>transparencia,\u00a0<\/strong>que define como el\u00a0<strong>manejo honesto<\/strong>\u00a0y adecuado de los recursos p\u00fablicos, as\u00ed como la\u00a0<strong>facilitaci\u00f3n de informaci\u00f3n p\u00fablica<\/strong>\u00a0desde los \u00d3rganos del Estado y las entidades privadas que administran recursos fiscales y\/o recursos naturales, de forma veraz, oportuna, comprensible y confiable.<\/p>\n<ul>\n<li><strong>\u00bfDe qu\u00e9 manera puede participar la ciudadan\u00eda?<\/strong><\/li>\n<\/ul>\n<p>En su\u00a0<a href=\"https:\/\/observatorioplanificacion.cepal.org\/sites\/default\/files\/instrument\/files\/LEY%20341.pdf\">art\u00edculo 6, la norma<\/a>\u00a0dice que \u201cson actores de la Participaci\u00f3n y Control Social,\u00a0<strong>la sociedad civil organizada<\/strong>, sin ning\u00fan tipo de discriminaci\u00f3n de sexo, color, edad, orientaci\u00f3n sexual, identidad de g\u00e9nero, origen, cultura, nacionalidad, ciudadan\u00eda, idioma, credo religioso, ideolog\u00eda, filiaci\u00f3n pol\u00edtica o filos\u00f3fica, estado civil, condici\u00f3n econ\u00f3mica o social, grado de instrucci\u00f3n y capacidades diferenciadas.<\/p>\n<p>Los tipos de actores pueden ser\u00a0<strong>org\u00e1nicos<\/strong>\u00a0(sectores sociales, juntas vecinales y\/o sindicales),\u00a0<strong>comunitarios<\/strong>\u00a0(naciones y pueblos ind\u00edgena originario campesinos) y\u00a0<strong>circunstanciales<\/strong>\u00a0(aquellos que se organizan para un fin determinado).<\/p>\n<p>Irahola se\u00f1al\u00f3 que una de las debilidades de la aplicaci\u00f3n del control social en Bolivia es la definici\u00f3n de qui\u00e9nes conforman la sociedad civil.<\/p>\n<p>\u201cA veces hay mucha gente que a nombre de la sociedad civil est\u00e1 haciendo un rol de gestor de autoridad o de servidor p\u00fablico, entonces ah\u00ed est\u00e1 siendo juez y parte. Tambi\u00e9n hay muchas instancias que solamente convocan a cierto sector (para planificar o rendir cuentas) y no convocan a los otros sectores de la sociedad civil\u201d, dijo.<\/p>\n<p>En su criterio, esto causa una sensaci\u00f3n falsa de control social y participaci\u00f3n social, adem\u00e1s de generar sectores que se sienten excluidos.<\/p>\n<ul>\n<li><strong>\u00bfQu\u00e9 es la rendici\u00f3n p\u00fablica de cuentas?<\/strong><\/li>\n<\/ul>\n<p>Adem\u00e1s del acceso a la informaci\u00f3n p\u00fablica, la ley establece la obligatoriedad de la rendici\u00f3n p\u00fablica de cuentas por parte de las instituciones del Estado.<\/p>\n<p>Art\u00edculo 33, par\u00e1grafo 5: \u201cRealizar peri\u00f3dicamente procesos de rendici\u00f3n p\u00fablica de cuentas econ\u00f3micas, pol\u00edticas, t\u00e9cnicas, administrativas y evaluaci\u00f3n abierta de resultados de gesti\u00f3n en el marco del plan estrat\u00e9gico institucional y la planificaci\u00f3n operativa anual\u201d.<\/p>\n<p>A partir de esto, las entidades p\u00fablicas han decidido generar espacios para las llamadas audiencias p\u00fablicas de rendici\u00f3n de cuentas. En el caso del Ejecutivo nacional se producen dos veces por a\u00f1o.<\/p>\n<p>Sin embargo, en criterio de Veizaga, estas actividades \u201cse constituyen en una pantomima, porque la poblaci\u00f3n no tiene acceso a la informaci\u00f3n veraz y completa para ejercer el control social sobre la gesti\u00f3n p\u00fablica\u201d, pues lo que se presenta es un reporte desde la perspectiva de la autoridad.<\/p>\n<p>Irahola lament\u00f3 tambi\u00e9n que al citar a las organizaciones sociales a estas rendiciones se validen los informes sin que haya un conocimiento exacto de sus contenidos.<\/p>\n<p>\u201cA veces son reuniones o asambleas o cumbres de una ma\u00f1ana o una tarde y la gente muchas veces asiste como a un seminario a escuchar. Pero la rendici\u00f3n de cuentas no es un espacio de socializaci\u00f3n de informaci\u00f3n, sino que deber\u00eda ser un espacio en el que se reciben observaciones de parte de la sociedad civil\u201d, precis\u00f3.<\/p>\n<p>Para ello, afirm\u00f3 Irahola, es imprescindible el acceso a la informaci\u00f3n p\u00fablica, oportuna, comprensible y transparente, de manera preliminar a estos encuentros.<\/p>\n<p>\u201cT\u00fa ves los informes del Ministerio de Econom\u00eda, con cuadros de presupuesto, de d\u00e9ficit, de deuda, etc\u00e9tera. Si un dirigente recibe esa informaci\u00f3n qu\u00e9 puede opinar sobre temas t\u00e9cnicos\u201d, cuestion\u00f3.<\/p>\n<h3><b>Fomentar la transparencia<\/b><\/h3>\n<p>Desde el punto de vista de Irahola, debe surgir de las entidades p\u00fablicas la obligaci\u00f3n de informar, tener unidades de transparencia o hacer que estas funcionen bien, y responder a las demandas de la sociedad que requiera de informaci\u00f3n espec\u00edfica de la gesti\u00f3n.<\/p>\n<p>\u201cAh\u00ed hay mucho que avanzar. Somos uno de los pocos pa\u00edses que todav\u00eda no tiene una ley nacional de acceso de acceso a la informaci\u00f3n p\u00fablica, es algo importante que hay que trabajar para ejercer un mayor derecho a la participaci\u00f3n. \u00bfc\u00f3mo puedes participar si no conoces c\u00f3mo est\u00e1 funcionando la gesti\u00f3n?\u201d, apunt\u00f3.<\/p>\n<p>El experto expres\u00f3 su temor en sentido de que la escasa promoci\u00f3n de un verdadero control social desanime a las nuevas generaciones, con serias consecuencias para la democracia.<\/p>\n<p>\u201cCorremos el peligro de bajar tambi\u00e9n la calidad de la democracia y con las generaciones j\u00f3venes esto es muy delicado porque pueden entender que la democracia no es algo que tenga importancia\u201d.<\/p>\n<\/body>","protected":false},"excerpt":{"rendered":"<p>Dos expertos explican los alcances de este derecho de la sociedad civil organizada y la importancia que tiene para ello la transparencia en la gesti\u00f3n de las entidades estatales. La participaci\u00f3n y control social, una prerrogativa de la ciudadan\u00eda establecida tanto por la Constituci\u00f3n Pol\u00edtica del Estado (CPE) como por ley espec\u00edfica, solo puede ser [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11816,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[62],"tags":[],"class_list":["post-11815","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nota-de-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acceder a la informaci\u00f3n p\u00fablica es una condici\u00f3n indispensable para ejercer la participaci\u00f3n y el control social - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acceder a la informaci\u00f3n p\u00fablica es una condici\u00f3n indispensable para ejercer la participaci\u00f3n y el control social - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Dos expertos explican los alcances de este derecho de la sociedad civil organizada y la importancia que tiene para ello la transparencia en la gesti\u00f3n de las entidades estatales. La participaci\u00f3n y control social, una prerrogativa de la ciudadan\u00eda establecida tanto por la Constituci\u00f3n Pol\u00edtica del Estado (CPE) como por ley espec\u00edfica, solo puede ser [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/\" \/>\n<meta property=\"og:site_name\" content=\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-10T18:41:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/11\/Control-social.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"922\" \/>\n\t<meta property=\"og:image:height\" content=\"462\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Fperiodismo\" \/>\n<meta name=\"twitter:site\" content=\"@Fperiodismo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/person\\\/766860617f341de7d6364a92b1495d9b\"},\"headline\":\"Acceder a la informaci\u00f3n p\u00fablica es una condici\u00f3n indispensable para ejercer la participaci\u00f3n y el control social\",\"datePublished\":\"2023-11-10T18:41:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\\\/\"},\"wordCount\":1512,\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Control-social.webp?fit=922%2C462&ssl=1\",\"articleSection\":[\"Nota de Prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\\\/\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\\\/\",\"name\":\"Acceder a la informaci\u00f3n p\u00fablica es una condici\u00f3n indispensable para ejercer la participaci\u00f3n y el control social - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Control-social.webp?fit=922%2C462&ssl=1\",\"datePublished\":\"2023-11-10T18:41:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Control-social.webp?fit=922%2C462&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Control-social.webp?fit=922%2C462&ssl=1\",\"width\":922,\"height\":462},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acceder a la informaci\u00f3n p\u00fablica es una condici\u00f3n indispensable para ejercer la participaci\u00f3n y el control social\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#website\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\",\"name\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"description\":\"Reflexionar a la opini\u00f3n p\u00fablica sobre la aprobaci\u00f3n de la Ley de Acceso a la Informaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#organization\",\"name\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\",\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-DIC.png?fit=656%2C330&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-DIC.png?fit=656%2C330&ssl=1\",\"width\":656,\"height\":330,\"caption\":\"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FundacionParaelPeriodismo\\\/\",\"https:\\\/\\\/x.com\\\/Fperiodismo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/#\\\/schema\\\/person\\\/766860617f341de7d6364a92b1495d9b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/475bf03b6c0001cfce6781f8d9b4949005e65d0c45592ae744a3fc5742074fc5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/475bf03b6c0001cfce6781f8d9b4949005e65d0c45592ae744a3fc5742074fc5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/475bf03b6c0001cfce6781f8d9b4949005e65d0c45592ae744a3fc5742074fc5?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\"],\"url\":\"https:\\\/\\\/fundacionperiodismo.org\\\/derecho-informacion-comunicacion\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acceder a la informaci\u00f3n p\u00fablica es una condici\u00f3n indispensable para ejercer la participaci\u00f3n y el control social - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/","og_locale":"es_ES","og_type":"article","og_title":"Acceder a la informaci\u00f3n p\u00fablica es una condici\u00f3n indispensable para ejercer la participaci\u00f3n y el control social - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","og_description":"Dos expertos explican los alcances de este derecho de la sociedad civil organizada y la importancia que tiene para ello la transparencia en la gesti\u00f3n de las entidades estatales. La participaci\u00f3n y control social, una prerrogativa de la ciudadan\u00eda establecida tanto por la Constituci\u00f3n Pol\u00edtica del Estado (CPE) como por ley espec\u00edfica, solo puede ser [&hellip;]","og_url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/","og_site_name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/","article_published_time":"2023-11-10T18:41:46+00:00","og_image":[{"width":922,"height":462,"url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/11\/Control-social.webp","type":"image\/webp"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@Fperiodismo","twitter_site":"@Fperiodismo","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/#article","isPartOf":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/"},"author":{"name":"admin","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/person\/766860617f341de7d6364a92b1495d9b"},"headline":"Acceder a la informaci\u00f3n p\u00fablica es una condici\u00f3n indispensable para ejercer la participaci\u00f3n y el control social","datePublished":"2023-11-10T18:41:46+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/"},"wordCount":1512,"publisher":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/11\/Control-social.webp?fit=922%2C462&ssl=1","articleSection":["Nota de Prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/","name":"Acceder a la informaci\u00f3n p\u00fablica es una condici\u00f3n indispensable para ejercer la participaci\u00f3n y el control social - Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","isPartOf":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/#primaryimage"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/11\/Control-social.webp?fit=922%2C462&ssl=1","datePublished":"2023-11-10T18:41:46+00:00","breadcrumb":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/#primaryimage","url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/11\/Control-social.webp?fit=922%2C462&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/11\/Control-social.webp?fit=922%2C462&ssl=1","width":922,"height":462},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/acceder-a-la-informacion-publica-es-una-condicion-indispensable-para-ejercer-la-participacion-y-el-control-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/"},{"@type":"ListItem","position":2,"name":"Acceder a la informaci\u00f3n p\u00fablica es una condici\u00f3n indispensable para ejercer la participaci\u00f3n y el control social"}]},{"@type":"WebSite","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#website","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/","name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","description":"Reflexionar a la opini\u00f3n p\u00fablica sobre la aprobaci\u00f3n de la Ley de Acceso a la Informaci\u00f3n","publisher":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#organization","name":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n","url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/07\/logo-DIC.png?fit=656%2C330&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2022\/07\/logo-DIC.png?fit=656%2C330&ssl=1","width":656,"height":330,"caption":"Derecho a la Informaci\u00f3n y Comunicaci\u00f3n"},"image":{"@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FundacionParaelPeriodismo\/","https:\/\/x.com\/Fperiodismo"]},{"@type":"Person","@id":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/#\/schema\/person\/766860617f341de7d6364a92b1495d9b","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/475bf03b6c0001cfce6781f8d9b4949005e65d0c45592ae744a3fc5742074fc5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/475bf03b6c0001cfce6781f8d9b4949005e65d0c45592ae744a3fc5742074fc5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/475bf03b6c0001cfce6781f8d9b4949005e65d0c45592ae744a3fc5742074fc5?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion"],"url":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-content\/uploads\/2023\/11\/Control-social.webp?fit=922%2C462&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/comments?post=11815"}],"version-history":[{"count":1,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11815\/revisions"}],"predecessor-version":[{"id":11817,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/posts\/11815\/revisions\/11817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/media\/11816"}],"wp:attachment":[{"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/media?parent=11815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/categories?post=11815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionperiodismo.org\/derecho-informacion-comunicacion\/wp-json\/wp\/v2\/tags?post=11815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}